{"id":9399,"date":"2023-11-23T15:33:30","date_gmt":"2023-11-23T14:33:30","guid":{"rendered":"https:\/\/prose.one\/engineering-makes-a-direct-impact-on-the-traveling-experience-for-passengers\/"},"modified":"2023-11-24T10:37:03","modified_gmt":"2023-11-24T09:37:03","slug":"engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus","status":"publish","type":"post","link":"https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/","title":{"rendered":"Engineering wirkt sich unmittelbar auf das Reiseerlebnis der Fahrg\u00e4ste aus"},"content":{"rendered":"<p>Folgen Sie uns in die faszinierende Welt der elektrischen Systeme und lassen Sie sich zeigen, wie die Elektrotechnik einen direkten Einfluss auf das Reiseerlebnis der Fahrg\u00e4ste hat.<\/p>\n<p>Modernisierungsmassnahmen an Z\u00fcgen verl\u00e4ngern die Nutzungsdauer des rollenden Materials. Sie bieten den Bahnbetreibern auch die M\u00f6glichkeit, das Reiseerlebnis f\u00fcr die Fahrg\u00e4ste zu verbessern und die Attraktivit\u00e4t des Verkehrs zu steigern.<\/p>\n<p>Die Installation von Wi-Fi-Zugang im Fahrgastraum und die richtige Verteilung von Steckdosen erm\u00f6glichen es den Pendlern, bei der Arbeit oder in der Freizeit in Verbindung zu bleiben.<\/p>\n<p>PROSE unterst\u00fctzt ihre Kunden bei der Integration der bordseitigen elektrischen Subsysteme w\u00e4hrend des gesamten Projekts. Der Prozess beginnt mit den ersten Phasen der Konzeptdefinition. Dann geht es weiter mit dem elektrischen und mechanischen Design, wobei sichergestellt wird, dass die bordseitige Integration mit den Eisenbahnvorschriften \u00fcbereinstimmt. Abschliessend werden die elektrischen Schaltpl\u00e4ne, Verdrahtungstabellen und die Komponentenliste ver\u00f6ffentlicht. PROSE entwirft auch die technischen Spezifikationen f\u00fcr die Lieferanten nach den Bed\u00fcrfnissen des Kunden.<\/p>\n<p>Wie k\u00f6nnen wir Sie bei Ihrem n\u00e4chsten Projekt unterst\u00fctzen? Kontaktieren Sie uns: <a href=\"https:\/\/prose.one\/de\/kontakt\/\">https:\/\/prose.one\/de\/kontakt\/<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Folgen Sie uns in die faszinierende Welt der elektrischen Systeme und lassen Sie sich zeigen, wie die Elektrotechnik einen direkten Einfluss auf das Reiseerlebnis der Fahrg\u00e4ste hat. Modernisierungsmassnahmen an Z\u00fcgen verl\u00e4ngern die Nutzungsdauer des rollenden Materials. Sie bieten den Bahnbetreibern auch die M\u00f6glichkeit, das Reiseerlebnis f\u00fcr die Fahrg\u00e4ste zu verbessern und die Attraktivit\u00e4t des Verkehrs [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9397,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117,129],"tags":[159],"class_list":["post-9399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-de","category-business-de","tag-business-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Engineering wirkt sich unmittelbar auf das Reiseerlebnis der Fahrg\u00e4ste aus - PROSE - Shaping tomorrow\u2019s mobility<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Engineering wirkt sich unmittelbar auf das Reiseerlebnis der Fahrg\u00e4ste aus - PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"og:description\" content=\"Folgen Sie uns in die faszinierende Welt der elektrischen Systeme und lassen Sie sich zeigen, wie die Elektrotechnik einen direkten Einfluss auf das Reiseerlebnis der Fahrg\u00e4ste hat. Modernisierungsmassnahmen an Z\u00fcgen verl\u00e4ngern die Nutzungsdauer des rollenden Materials. Sie bieten den Bahnbetreibern auch die M\u00f6glichkeit, das Reiseerlebnis f\u00fcr die Fahrg\u00e4ste zu verbessern und die Attraktivit\u00e4t des Verkehrs [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/\" \/>\n<meta property=\"og:site_name\" content=\"PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-23T14:33:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-24T09:37:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prose.one\/wp-content\/uploads\/20231123_ele-services_Nicolo-post.jpg.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2250\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Prose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prose\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\\\/\"},\"author\":{\"name\":\"Prose\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\"},\"headline\":\"Engineering wirkt sich unmittelbar auf das Reiseerlebnis der Fahrg\u00e4ste aus\",\"datePublished\":\"2023-11-23T14:33:30+00:00\",\"dateModified\":\"2023-11-24T09:37:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\\\/\"},\"wordCount\":199,\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20231123_ele-services_Nicolo-post.jpg.png\",\"keywords\":[\"Business\"],\"articleSection\":[\"Alle News\",\"Business\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\\\/\",\"name\":\"Engineering wirkt sich unmittelbar auf das Reiseerlebnis der Fahrg\u00e4ste aus - PROSE - Shaping tomorrow\u2019s mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20231123_ele-services_Nicolo-post.jpg.png\",\"datePublished\":\"2023-11-23T14:33:30+00:00\",\"dateModified\":\"2023-11-24T09:37:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prose.one\\\/de\\\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20231123_ele-services_Nicolo-post.jpg.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20231123_ele-services_Nicolo-post.jpg.png\",\"width\":2250,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/prose.one\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Engineering wirkt sich unmittelbar auf das Reiseerlebnis der Fahrg\u00e4ste aus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"name\":\"PROSE Shaping tomorrow\u2019s mobility\",\"description\":\"Shaping tomorrow\u2019s mobility\",\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prose.one\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\",\"name\":\"PROSE\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"width\":1182,\"height\":326,\"caption\":\"PROSE\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prose-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\",\"name\":\"Prose\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/author\\\/adminprose\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Engineering wirkt sich unmittelbar auf das Reiseerlebnis der Fahrg\u00e4ste aus - PROSE - Shaping tomorrow\u2019s mobility","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/","og_locale":"de_DE","og_type":"article","og_title":"Engineering wirkt sich unmittelbar auf das Reiseerlebnis der Fahrg\u00e4ste aus - PROSE - Shaping tomorrow\u2019s mobility","og_description":"Folgen Sie uns in die faszinierende Welt der elektrischen Systeme und lassen Sie sich zeigen, wie die Elektrotechnik einen direkten Einfluss auf das Reiseerlebnis der Fahrg\u00e4ste hat. Modernisierungsmassnahmen an Z\u00fcgen verl\u00e4ngern die Nutzungsdauer des rollenden Materials. Sie bieten den Bahnbetreibern auch die M\u00f6glichkeit, das Reiseerlebnis f\u00fcr die Fahrg\u00e4ste zu verbessern und die Attraktivit\u00e4t des Verkehrs [&hellip;]","og_url":"https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/","og_site_name":"PROSE - Shaping tomorrow\u2019s mobility","article_published_time":"2023-11-23T14:33:30+00:00","article_modified_time":"2023-11-24T09:37:03+00:00","og_image":[{"url":"https:\/\/prose.one\/wp-content\/uploads\/20231123_ele-services_Nicolo-post.jpg.png","width":2250,"height":1500,"type":"image\/png"}],"author":"Prose","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Prose","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/#article","isPartOf":{"@id":"https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/"},"author":{"name":"Prose","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9"},"headline":"Engineering wirkt sich unmittelbar auf das Reiseerlebnis der Fahrg\u00e4ste aus","datePublished":"2023-11-23T14:33:30+00:00","dateModified":"2023-11-24T09:37:03+00:00","mainEntityOfPage":{"@id":"https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/"},"wordCount":199,"publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"image":{"@id":"https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/20231123_ele-services_Nicolo-post.jpg.png","keywords":["Business"],"articleSection":["Alle News","Business"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/","url":"https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/","name":"Engineering wirkt sich unmittelbar auf das Reiseerlebnis der Fahrg\u00e4ste aus - PROSE - Shaping tomorrow\u2019s mobility","isPartOf":{"@id":"https:\/\/prose.one\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/#primaryimage"},"image":{"@id":"https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/20231123_ele-services_Nicolo-post.jpg.png","datePublished":"2023-11-23T14:33:30+00:00","dateModified":"2023-11-24T09:37:03+00:00","breadcrumb":{"@id":"https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/#primaryimage","url":"https:\/\/prose.one\/wp-content\/uploads\/20231123_ele-services_Nicolo-post.jpg.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/20231123_ele-services_Nicolo-post.jpg.png","width":2250,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/prose.one\/de\/engineering-wirkt-sich-unmittelbar-auf-das-reiseerlebnis-der-fahrgaeste-aus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/prose.one\/de\/"},{"@type":"ListItem","position":2,"name":"Engineering wirkt sich unmittelbar auf das Reiseerlebnis der Fahrg\u00e4ste aus"}]},{"@type":"WebSite","@id":"https:\/\/prose.one\/de\/#website","url":"https:\/\/prose.one\/de\/","name":"PROSE Shaping tomorrow\u2019s mobility","description":"Shaping tomorrow\u2019s mobility","publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prose.one\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/prose.one\/de\/#organization","name":"PROSE","url":"https:\/\/prose.one\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/","url":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","width":1182,"height":326,"caption":"PROSE"},"image":{"@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/prose-group"]},{"@type":"Person","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9","name":"Prose","url":"https:\/\/prose.one\/de\/author\/adminprose\/"}]}},"_links":{"self":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/9399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/comments?post=9399"}],"version-history":[{"count":2,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/9399\/revisions"}],"predecessor-version":[{"id":9401,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/9399\/revisions\/9401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media\/9397"}],"wp:attachment":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media?parent=9399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/categories?post=9399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/tags?post=9399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}