{"id":9277,"date":"2023-11-07T19:55:58","date_gmt":"2023-11-07T18:55:58","guid":{"rendered":"https:\/\/prose.one\/reducing-noise-and-wear\/"},"modified":"2023-11-07T20:02:30","modified_gmt":"2023-11-07T19:02:30","slug":"reduzierung-von-laerm-und-verschleiss","status":"publish","type":"post","link":"https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/","title":{"rendered":"Reduzierung von L\u00e4rm und Verschleiss"},"content":{"rendered":"<p>Wie k\u00f6nnen L\u00e4rm und Verschleiss auf ein Maximum reduziert werden? Mit Sensorik und k\u00fcnstlicher Intelligenz (KI)!<\/p>\n<p>Im Rahmen des vom Bundesamt f\u00fcr Verkehr (BAV) gef\u00f6rderten Forschungsprojekts mit PROSE, BERNMOBIL, LeanBI AG und Parametric SDS f\u00fcr eine bedarfsgerechte Schienenkopfkonditionierung standen aktuell die ersten Tests an.<\/p>\n<p>Sehen Sie im Video, wie PROSE-Mitarbeiter Felix Saur die Versuche mit der HoloLens protokolliert.<\/p>\n<div style=\"width: 2250px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-9277-1\" width=\"2250\" height=\"1500\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/prose.one\/wp-content\/uploads\/fahrt2.mp4?_=1\" \/><a href=\"https:\/\/prose.one\/wp-content\/uploads\/fahrt2.mp4\">https:\/\/prose.one\/wp-content\/uploads\/fahrt2.mp4<\/a><\/video><\/div>\n<p>&nbsp;<\/p>\n<p>PROSE kann Ihr L\u00f6sungsanbieter sein. <a href=\"https:\/\/prose.one\/de\/kontakt\/\">Kontaktieren Sie uns noch heute.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie k\u00f6nnen L\u00e4rm und Verschleiss auf ein Maximum reduziert werden? Mit Sensorik und k\u00fcnstlicher Intelligenz (KI)! Im Rahmen des vom Bundesamt f\u00fcr Verkehr (BAV) gef\u00f6rderten Forschungsprojekts mit PROSE, BERNMOBIL, LeanBI AG und Parametric SDS f\u00fcr eine bedarfsgerechte Schienenkopfkonditionierung standen aktuell die ersten Tests an. Sehen Sie im Video, wie PROSE-Mitarbeiter Felix Saur die Versuche mit [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":9275,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117,129],"tags":[159],"class_list":["post-9277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-de","category-business-de","tag-business-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reduzierung von L\u00e4rm und Verschleiss - PROSE - Shaping tomorrow\u2019s mobility<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reduzierung von L\u00e4rm und Verschleiss - PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"og:description\" content=\"Wie k\u00f6nnen L\u00e4rm und Verschleiss auf ein Maximum reduziert werden? Mit Sensorik und k\u00fcnstlicher Intelligenz (KI)! Im Rahmen des vom Bundesamt f\u00fcr Verkehr (BAV) gef\u00f6rderten Forschungsprojekts mit PROSE, BERNMOBIL, LeanBI AG und Parametric SDS f\u00fcr eine bedarfsgerechte Schienenkopfkonditionierung standen aktuell die ersten Tests an. Sehen Sie im Video, wie PROSE-Mitarbeiter Felix Saur die Versuche mit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/\" \/>\n<meta property=\"og:site_name\" content=\"PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-07T18:55:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-07T19:02:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prose.one\/wp-content\/uploads\/Unbenannt1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2250\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Livia In-Albon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Livia In-Albon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/reduzierung-von-laerm-und-verschleiss\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/reduzierung-von-laerm-und-verschleiss\\\/\"},\"author\":{\"name\":\"Livia In-Albon\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/5dcf46831d13ad7f4ecbe64f70764ffe\"},\"headline\":\"Reduzierung von L\u00e4rm und Verschleiss\",\"datePublished\":\"2023-11-07T18:55:58+00:00\",\"dateModified\":\"2023-11-07T19:02:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/reduzierung-von-laerm-und-verschleiss\\\/\"},\"wordCount\":94,\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/reduzierung-von-laerm-und-verschleiss\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/Unbenannt1.png\",\"keywords\":[\"Business\"],\"articleSection\":[\"Alle News\",\"Business\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/reduzierung-von-laerm-und-verschleiss\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/reduzierung-von-laerm-und-verschleiss\\\/\",\"name\":\"Reduzierung von L\u00e4rm und Verschleiss - PROSE - Shaping tomorrow\u2019s mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/reduzierung-von-laerm-und-verschleiss\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/reduzierung-von-laerm-und-verschleiss\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/Unbenannt1.png\",\"datePublished\":\"2023-11-07T18:55:58+00:00\",\"dateModified\":\"2023-11-07T19:02:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/reduzierung-von-laerm-und-verschleiss\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prose.one\\\/de\\\/reduzierung-von-laerm-und-verschleiss\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/reduzierung-von-laerm-und-verschleiss\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/Unbenannt1.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/Unbenannt1.png\",\"width\":2250,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/reduzierung-von-laerm-und-verschleiss\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/prose.one\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reduzierung von L\u00e4rm und Verschleiss\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"name\":\"PROSE Shaping tomorrow\u2019s mobility\",\"description\":\"Shaping tomorrow\u2019s mobility\",\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prose.one\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\",\"name\":\"PROSE\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"width\":1182,\"height\":326,\"caption\":\"PROSE\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prose-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/5dcf46831d13ad7f4ecbe64f70764ffe\",\"name\":\"Livia In-Albon\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/author\\\/livia-in-albon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reduzierung von L\u00e4rm und Verschleiss - PROSE - Shaping tomorrow\u2019s mobility","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/","og_locale":"de_DE","og_type":"article","og_title":"Reduzierung von L\u00e4rm und Verschleiss - PROSE - Shaping tomorrow\u2019s mobility","og_description":"Wie k\u00f6nnen L\u00e4rm und Verschleiss auf ein Maximum reduziert werden? Mit Sensorik und k\u00fcnstlicher Intelligenz (KI)! Im Rahmen des vom Bundesamt f\u00fcr Verkehr (BAV) gef\u00f6rderten Forschungsprojekts mit PROSE, BERNMOBIL, LeanBI AG und Parametric SDS f\u00fcr eine bedarfsgerechte Schienenkopfkonditionierung standen aktuell die ersten Tests an. Sehen Sie im Video, wie PROSE-Mitarbeiter Felix Saur die Versuche mit [&hellip;]","og_url":"https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/","og_site_name":"PROSE - Shaping tomorrow\u2019s mobility","article_published_time":"2023-11-07T18:55:58+00:00","article_modified_time":"2023-11-07T19:02:30+00:00","og_image":[{"width":2250,"height":1500,"url":"https:\/\/prose.one\/wp-content\/uploads\/Unbenannt1.png","type":"image\/png"}],"author":"Livia In-Albon","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Livia In-Albon","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/#article","isPartOf":{"@id":"https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/"},"author":{"name":"Livia In-Albon","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/5dcf46831d13ad7f4ecbe64f70764ffe"},"headline":"Reduzierung von L\u00e4rm und Verschleiss","datePublished":"2023-11-07T18:55:58+00:00","dateModified":"2023-11-07T19:02:30+00:00","mainEntityOfPage":{"@id":"https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/"},"wordCount":94,"publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"image":{"@id":"https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/Unbenannt1.png","keywords":["Business"],"articleSection":["Alle News","Business"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/","url":"https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/","name":"Reduzierung von L\u00e4rm und Verschleiss - PROSE - Shaping tomorrow\u2019s mobility","isPartOf":{"@id":"https:\/\/prose.one\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/#primaryimage"},"image":{"@id":"https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/Unbenannt1.png","datePublished":"2023-11-07T18:55:58+00:00","dateModified":"2023-11-07T19:02:30+00:00","breadcrumb":{"@id":"https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/#primaryimage","url":"https:\/\/prose.one\/wp-content\/uploads\/Unbenannt1.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/Unbenannt1.png","width":2250,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/prose.one\/de\/reduzierung-von-laerm-und-verschleiss\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/prose.one\/de\/"},{"@type":"ListItem","position":2,"name":"Reduzierung von L\u00e4rm und Verschleiss"}]},{"@type":"WebSite","@id":"https:\/\/prose.one\/de\/#website","url":"https:\/\/prose.one\/de\/","name":"PROSE Shaping tomorrow\u2019s mobility","description":"Shaping tomorrow\u2019s mobility","publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prose.one\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/prose.one\/de\/#organization","name":"PROSE","url":"https:\/\/prose.one\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/","url":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","width":1182,"height":326,"caption":"PROSE"},"image":{"@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/prose-group"]},{"@type":"Person","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/5dcf46831d13ad7f4ecbe64f70764ffe","name":"Livia In-Albon","url":"https:\/\/prose.one\/de\/author\/livia-in-albon\/"}]}},"_links":{"self":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/9277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/comments?post=9277"}],"version-history":[{"count":3,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/9277\/revisions"}],"predecessor-version":[{"id":9281,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/9277\/revisions\/9281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media\/9275"}],"wp:attachment":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media?parent=9277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/categories?post=9277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/tags?post=9277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}