{"id":9186,"date":"2023-10-30T11:31:44","date_gmt":"2023-10-30T10:31:44","guid":{"rendered":"https:\/\/prose.one\/let-us-contribute-to-your-success-with-etcs\/"},"modified":"2023-10-30T11:49:39","modified_gmt":"2023-10-30T10:49:39","slug":"lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen","status":"publish","type":"post","link":"https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/","title":{"rendered":"Lassen Sie uns zu Ihrem Erfolg mit ETCS beitragen!"},"content":{"rendered":"<div>Sie wollen die Komplexit\u00e4t des European Train Control Systems ETCS bew\u00e4ltigen? Mit unserer Kompetenz in der Schienenfahrzeugtechnik sind wir f\u00fcr Sie da!<\/div>\n<div>Wir von PROSE sind Ihre vertrauensw\u00fcrdigen Berater und L\u00f6sungsanbieter, die Sie bei Ihren ETCS-Herausforderungen begleiten und unterst\u00fctzen.<\/div>\n<div><\/div>\n<p><strong>Unser Fachwissen:<\/strong><\/p>\n<ul>\n<li><strong>Beratung &amp; Projektleitung:<\/strong> Wir entwickeln f\u00fcr Sie einen strategischen Fahrplan, der den Betrieb und das Asset Management optimiert. Dar\u00fcber hinaus verf\u00fcgen wir \u00fcber umfangreiche Erfahrungen im Beschaffungsmanagement und bei der Einf\u00fchrung von ETCS-OB.<\/li>\n<li><strong>Technik und Integration:<\/strong> Z\u00e4hlen Sie auf uns, wenn es um Retrofitting, Onboard-Integration, Fahrzeugzulassung sowie Inbetriebnahme- und Pr\u00fcfdienste geht.<\/li>\n<\/ul>\n<p>Setzen Sie sich mit uns in Verbindung, um zu erfahren, wie wir Ihren Bahnbetrieb verbessern und ETCS f\u00fcr Sie nutzbar machen k\u00f6nnen.<\/p>\n<p><strong>Verantwortlich pro Markt<br \/>\n<\/strong>Serviceleiter Engineering:<br \/>\n<a href=\"https:\/\/www.linkedin.com\/feed\/\"><strong>Riccardo Loni<\/strong><\/a><br \/>\n<a href=\"mailto:riccardo.loni@prose.one\">riccardo.loni@prose.one<\/a><\/p>\n<p>Serviceleiter Beratung:<br \/>\n<a href=\"https:\/\/www.linkedin.com\/feed\/\"><strong>Finn Wirth<\/strong><\/a><br \/>\n<a href=\"mailto:finn.wirth@prose.one\">finn.wirth@prose.one<\/a><\/p>\n<p>Rollout International:<br \/>\n<a href=\"https:\/\/www.linkedin.com\/feed\/\"><strong>Christoph Gyr<\/strong><\/a><br \/>\n<a href=\"mailto:christoph.gyr@prose.one\">christoph.gyr@prose.one<\/a><\/p>\n<p>Rollout \u00d6sterreich:<br \/>\n<a href=\"https:\/\/www.linkedin.com\/feed\/\"><strong>Josef Kometer<\/strong><\/a><br \/>\n<a href=\"mailto:josef.kometer@prose.one\">josef.kometer@prose.one<\/a><\/p>\n<p>Rollout Deutschland:<br \/>\n<a href=\"https:\/\/www.linkedin.com\/feed\/\"><strong>Roland Haun<\/strong><\/a><br \/>\n<a href=\"mailto:roland.haun@prose.one\">roland.haun@prose.one<\/a><\/p>\n<p>Rollout Schweiz:<br \/>\n<a href=\"https:\/\/www.linkedin.com\/feed\/\"><strong>Rolf M\u00fchlemann<\/strong><\/a><br \/>\n<a href=\"mailto:rolf.muhlemann@prose.one\">rolf.muhlemann@prose.one<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie wollen die Komplexit\u00e4t des European Train Control Systems ETCS bew\u00e4ltigen? Mit unserer Kompetenz in der Schienenfahrzeugtechnik sind wir f\u00fcr Sie da! Wir von PROSE sind Ihre vertrauensw\u00fcrdigen Berater und L\u00f6sungsanbieter, die Sie bei Ihren ETCS-Herausforderungen begleiten und unterst\u00fctzen. Unser Fachwissen: Beratung &amp; Projektleitung: Wir entwickeln f\u00fcr Sie einen strategischen Fahrplan, der den Betrieb und [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9178,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117,129],"tags":[159],"class_list":["post-9186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-de","category-business-de","tag-business-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lassen Sie uns zu Ihrem Erfolg mit ETCS beitragen! - PROSE - Shaping tomorrow\u2019s mobility<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lassen Sie uns zu Ihrem Erfolg mit ETCS beitragen! - PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"og:description\" content=\"Sie wollen die Komplexit\u00e4t des European Train Control Systems ETCS bew\u00e4ltigen? Mit unserer Kompetenz in der Schienenfahrzeugtechnik sind wir f\u00fcr Sie da! Wir von PROSE sind Ihre vertrauensw\u00fcrdigen Berater und L\u00f6sungsanbieter, die Sie bei Ihren ETCS-Herausforderungen begleiten und unterst\u00fctzen. Unser Fachwissen: Beratung &amp; Projektleitung: Wir entwickeln f\u00fcr Sie einen strategischen Fahrplan, der den Betrieb und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/\" \/>\n<meta property=\"og:site_name\" content=\"PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-30T10:31:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-30T10:49:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prose.one\/wp-content\/uploads\/20231030_ETCS_Pitch.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1092\" \/>\n\t<meta property=\"og:image:height\" content=\"728\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Prose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prose\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\\\/\"},\"author\":{\"name\":\"Prose\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\"},\"headline\":\"Lassen Sie uns zu Ihrem Erfolg mit ETCS beitragen!\",\"datePublished\":\"2023-10-30T10:31:44+00:00\",\"dateModified\":\"2023-10-30T10:49:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\\\/\"},\"wordCount\":189,\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20231030_ETCS_Pitch.png\",\"keywords\":[\"Business\"],\"articleSection\":[\"Alle News\",\"Business\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\\\/\",\"name\":\"Lassen Sie uns zu Ihrem Erfolg mit ETCS beitragen! - PROSE - Shaping tomorrow\u2019s mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20231030_ETCS_Pitch.png\",\"datePublished\":\"2023-10-30T10:31:44+00:00\",\"dateModified\":\"2023-10-30T10:49:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prose.one\\\/de\\\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20231030_ETCS_Pitch.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20231030_ETCS_Pitch.png\",\"width\":1092,\"height\":728},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/prose.one\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lassen Sie uns zu Ihrem Erfolg mit ETCS beitragen!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"name\":\"PROSE Shaping tomorrow\u2019s mobility\",\"description\":\"Shaping tomorrow\u2019s mobility\",\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prose.one\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\",\"name\":\"PROSE\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"width\":1182,\"height\":326,\"caption\":\"PROSE\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prose-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\",\"name\":\"Prose\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/author\\\/adminprose\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lassen Sie uns zu Ihrem Erfolg mit ETCS beitragen! - PROSE - Shaping tomorrow\u2019s mobility","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/","og_locale":"de_DE","og_type":"article","og_title":"Lassen Sie uns zu Ihrem Erfolg mit ETCS beitragen! - PROSE - Shaping tomorrow\u2019s mobility","og_description":"Sie wollen die Komplexit\u00e4t des European Train Control Systems ETCS bew\u00e4ltigen? Mit unserer Kompetenz in der Schienenfahrzeugtechnik sind wir f\u00fcr Sie da! Wir von PROSE sind Ihre vertrauensw\u00fcrdigen Berater und L\u00f6sungsanbieter, die Sie bei Ihren ETCS-Herausforderungen begleiten und unterst\u00fctzen. Unser Fachwissen: Beratung &amp; Projektleitung: Wir entwickeln f\u00fcr Sie einen strategischen Fahrplan, der den Betrieb und [&hellip;]","og_url":"https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/","og_site_name":"PROSE - Shaping tomorrow\u2019s mobility","article_published_time":"2023-10-30T10:31:44+00:00","article_modified_time":"2023-10-30T10:49:39+00:00","og_image":[{"width":1092,"height":728,"url":"https:\/\/prose.one\/wp-content\/uploads\/20231030_ETCS_Pitch.png","type":"image\/png"}],"author":"Prose","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Prose","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/#article","isPartOf":{"@id":"https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/"},"author":{"name":"Prose","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9"},"headline":"Lassen Sie uns zu Ihrem Erfolg mit ETCS beitragen!","datePublished":"2023-10-30T10:31:44+00:00","dateModified":"2023-10-30T10:49:39+00:00","mainEntityOfPage":{"@id":"https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/"},"wordCount":189,"publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"image":{"@id":"https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/20231030_ETCS_Pitch.png","keywords":["Business"],"articleSection":["Alle News","Business"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/","url":"https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/","name":"Lassen Sie uns zu Ihrem Erfolg mit ETCS beitragen! - PROSE - Shaping tomorrow\u2019s mobility","isPartOf":{"@id":"https:\/\/prose.one\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/#primaryimage"},"image":{"@id":"https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/20231030_ETCS_Pitch.png","datePublished":"2023-10-30T10:31:44+00:00","dateModified":"2023-10-30T10:49:39+00:00","breadcrumb":{"@id":"https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/#primaryimage","url":"https:\/\/prose.one\/wp-content\/uploads\/20231030_ETCS_Pitch.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/20231030_ETCS_Pitch.png","width":1092,"height":728},{"@type":"BreadcrumbList","@id":"https:\/\/prose.one\/de\/lassen-sie-uns-zu-ihrem-erfolg-mit-etcs-beitragen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/prose.one\/de\/"},{"@type":"ListItem","position":2,"name":"Lassen Sie uns zu Ihrem Erfolg mit ETCS beitragen!"}]},{"@type":"WebSite","@id":"https:\/\/prose.one\/de\/#website","url":"https:\/\/prose.one\/de\/","name":"PROSE Shaping tomorrow\u2019s mobility","description":"Shaping tomorrow\u2019s mobility","publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prose.one\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/prose.one\/de\/#organization","name":"PROSE","url":"https:\/\/prose.one\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/","url":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","width":1182,"height":326,"caption":"PROSE"},"image":{"@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/prose-group"]},{"@type":"Person","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9","name":"Prose","url":"https:\/\/prose.one\/de\/author\/adminprose\/"}]}},"_links":{"self":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/9186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/comments?post=9186"}],"version-history":[{"count":5,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/9186\/revisions"}],"predecessor-version":[{"id":9192,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/9186\/revisions\/9192"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media\/9178"}],"wp:attachment":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media?parent=9186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/categories?post=9186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/tags?post=9186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}