{"id":9115,"date":"2023-10-23T14:58:00","date_gmt":"2023-10-23T13:58:00","guid":{"rendered":"https:\/\/prose.one\/mechanical-design-and-system-integration\/"},"modified":"2023-11-24T13:19:11","modified_gmt":"2023-11-24T12:19:11","slug":"mechanische-konstruktion-und-system-integration","status":"publish","type":"post","link":"https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/","title":{"rendered":"Mechanische Konstruktion und Systemintegration"},"content":{"rendered":"<h3 class=\"detail\">Kunde: Verschiedene Kunden<\/h3>\n<h4>Projektaufgaben<\/h4>\n<ul>\n<li>Entwicklungsprojekte:\n<ul>\n<li>Komplette Drehgestellkonstruktion gem\u00e4ss EN 15085<\/li>\n<li>Komplette Wagenkastenkonstruktion gem\u00e4ss EN 15085<\/li>\n<li>Innenraum- und Layoutgestaltung<\/li>\n<li>Systemintegration (z.B. T\u00fcren, Bremssystem, HVAC, Kupplung etc.)<\/li>\n<\/ul>\n<\/li>\n<li>Projekte zur Modernisierung von Fahrzeugen:\n<ul>\n<li>Innenarchitektur<\/li>\n<li>Layout-Konzepte<\/li>\n<li>Systemintegration (z.B. ATC, Infotainmentsysteme, Magnetschienenbremse, Klimaanlage etc.)<\/li>\n<\/ul>\n<\/li>\n<li>Nischenentwicklungsprojekte (z.B. Spurwechsel- und Zahnradbahndrehgestelle, People Mover- oder Magnetschwebesysteme etc.)<\/li>\n<li>Kompetenzen im Bereich strukturelles Kleben und Schweissen:\n<ul>\n<li>Strukturelles Kleben nach DIN 6701-3 (A1) \/ EN 17460<\/li>\n<li>Schweissen nach EN 15085-2 (CL 1)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h4>Unsere Umsetzung<\/h4>\n<p>Unser Schwerpunkt liegt auf der Herstellbarkeit und Instand-haltbarkeit eines Fahrzeugs. Wir bieten durchdachte L\u00f6sun-gen f\u00fcr alle unsere Entw\u00fcrfe und stehen in direktem Aus-tausch mit unseren Kunden, um sicherzustellen, dass der Designprozess in kurzer Zeit abgeschlossen werden kann.<\/p>\n<h4>Kundennutzen<\/h4>\n<p>Mit 3D-Modellansichten geben wir visuelle Antworten auf Ihre Ideen oder Gedanken. Wir haben eine agile Arbeitsweise und k\u00f6nnen sicherstellen, dass Ihr Feedback die visuelle Idee pr\u00e4gt und zu ihrer Vollendung beitr\u00e4gt. Bereits in einem fr\u00fc-hen Stadium des Designprozesses stellt das PROSE-Designerteam sicher, dass der Konzeptentwurf der Konstruk-tion realisierbar ist. Unsere Flexibilit\u00e4t erm\u00f6glicht es uns, sehr kurzfristig auf Ihre W\u00fcnsche einzugehen. Wir bieten eine komplette Dokumentation f\u00fcr Beschaffung und Fertigung.<\/p>\n<p><a href=\"https:\/\/prose.one\/de\/alle-unsere-dienstleistungen\/\"><img decoding=\"async\" class=\"alignnone wp-image-7588\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Mechanische-Fahrzeug-Systemtechnik-Mechanical-vehicle-systems-engineering.svg\" alt=\"\" width=\"155\" \/><\/a>\u00a0<a href=\"https:\/\/prose.one\/de\/alle-unsere-dienstleistungen\/\"><img decoding=\"async\" class=\"alignnone wp-image-7590\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Modernisierung-Modernisation.svg\" alt=\"\" width=\"155\" \/><\/a> <a href=\"https:\/\/prose.one\/de\/alle-unsere-dienstleistungen\/\"><img decoding=\"async\" class=\"alignnone wp-image-7608\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Technische-Dokumentation-Documentation-services.svg\" alt=\"\" width=\"155\" \/><\/a> <a href=\"https:\/\/prose.one\/de\/alle-unsere-dienstleistungen\/\"><img decoding=\"async\" class=\"alignnone wp-image-7596\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Prufstande-Test-benches-facilities.svg\" alt=\"\" width=\"155\" height=\"0\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kunde: Verschiedene Kunden Projektaufgaben Entwicklungsprojekte: Komplette Drehgestellkonstruktion gem\u00e4ss EN 15085 Komplette Wagenkastenkonstruktion gem\u00e4ss EN 15085 Innenraum- und Layoutgestaltung Systemintegration (z.B. T\u00fcren, Bremssystem, HVAC, Kupplung etc.) Projekte zur Modernisierung von Fahrzeugen: Innenarchitektur Layout-Konzepte Systemintegration (z.B. ATC, Infotainmentsysteme, Magnetschienenbremse, Klimaanlage etc.) Nischenentwicklungsprojekte (z.B. Spurwechsel- und Zahnradbahndrehgestelle, People Mover- oder Magnetschwebesysteme etc.) Kompetenzen im Bereich strukturelles Kleben und [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9405,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[138,132,135,134,130],"tags":[170,171,183,120],"class_list":["post-9115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ausgewahlte-projekte","category-ihr-schienenfahrzeug-bauen","category-ihre-flotte-fit-machen","category-innovation-der-mobilitat-von-morgen","category-categories-referenzen","tag-mechanische-fahrzeug-systemtechnik","tag-modernisierung","tag-prufstande","tag-technische-dokumentation-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mechanische Konstruktion und Systemintegration - PROSE - Shaping tomorrow\u2019s mobility<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mechanische Konstruktion und Systemintegration - PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"og:description\" content=\"Kunde: Verschiedene Kunden Projektaufgaben Entwicklungsprojekte: Komplette Drehgestellkonstruktion gem\u00e4ss EN 15085 Komplette Wagenkastenkonstruktion gem\u00e4ss EN 15085 Innenraum- und Layoutgestaltung Systemintegration (z.B. T\u00fcren, Bremssystem, HVAC, Kupplung etc.) Projekte zur Modernisierung von Fahrzeugen: Innenarchitektur Layout-Konzepte Systemintegration (z.B. ATC, Infotainmentsysteme, Magnetschienenbremse, Klimaanlage etc.) Nischenentwicklungsprojekte (z.B. Spurwechsel- und Zahnradbahndrehgestelle, People Mover- oder Magnetschwebesysteme etc.) Kompetenzen im Bereich strukturelles Kleben und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/\" \/>\n<meta property=\"og:site_name\" content=\"PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-23T13:58:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-24T12:19:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prose.one\/wp-content\/uploads\/MicrosoftTeams-image-32.png\" \/>\n\t<meta property=\"og:image:width\" content=\"922\" \/>\n\t<meta property=\"og:image:height\" content=\"698\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Prose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prose\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/mechanische-konstruktion-und-system-integration\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/mechanische-konstruktion-und-system-integration\\\/\"},\"author\":{\"name\":\"Prose\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\"},\"headline\":\"Mechanische Konstruktion und Systemintegration\",\"datePublished\":\"2023-10-23T13:58:00+00:00\",\"dateModified\":\"2023-11-24T12:19:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/mechanische-konstruktion-und-system-integration\\\/\"},\"wordCount\":196,\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/mechanische-konstruktion-und-system-integration\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/MicrosoftTeams-image-32.png\",\"keywords\":[\"Mechanische Fahrzeug- &amp; Systemtechnik\",\"Modernisierung\",\"Pr\u00fcfst\u00e4nde\",\"Technische Dokumentation\"],\"articleSection\":[\"Ausgew\u00e4hlte Projekte\",\"Ihr Schienenfahrzeug bauen\",\"Ihre Flotte fit machen\",\"Innovation der Mobilit\u00e4t von morgen\",\"Kategorien Referenzen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/mechanische-konstruktion-und-system-integration\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/mechanische-konstruktion-und-system-integration\\\/\",\"name\":\"Mechanische Konstruktion und Systemintegration - PROSE - Shaping tomorrow\u2019s mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/mechanische-konstruktion-und-system-integration\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/mechanische-konstruktion-und-system-integration\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/MicrosoftTeams-image-32.png\",\"datePublished\":\"2023-10-23T13:58:00+00:00\",\"dateModified\":\"2023-11-24T12:19:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/mechanische-konstruktion-und-system-integration\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prose.one\\\/de\\\/mechanische-konstruktion-und-system-integration\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/mechanische-konstruktion-und-system-integration\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/MicrosoftTeams-image-32.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/MicrosoftTeams-image-32.png\",\"width\":922,\"height\":698},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/mechanische-konstruktion-und-system-integration\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/prose.one\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mechanische Konstruktion und Systemintegration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"name\":\"PROSE Shaping tomorrow\u2019s mobility\",\"description\":\"Shaping tomorrow\u2019s mobility\",\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prose.one\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\",\"name\":\"PROSE\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"width\":1182,\"height\":326,\"caption\":\"PROSE\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prose-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\",\"name\":\"Prose\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/author\\\/adminprose\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mechanische Konstruktion und Systemintegration - PROSE - Shaping tomorrow\u2019s mobility","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/","og_locale":"de_DE","og_type":"article","og_title":"Mechanische Konstruktion und Systemintegration - PROSE - Shaping tomorrow\u2019s mobility","og_description":"Kunde: Verschiedene Kunden Projektaufgaben Entwicklungsprojekte: Komplette Drehgestellkonstruktion gem\u00e4ss EN 15085 Komplette Wagenkastenkonstruktion gem\u00e4ss EN 15085 Innenraum- und Layoutgestaltung Systemintegration (z.B. T\u00fcren, Bremssystem, HVAC, Kupplung etc.) Projekte zur Modernisierung von Fahrzeugen: Innenarchitektur Layout-Konzepte Systemintegration (z.B. ATC, Infotainmentsysteme, Magnetschienenbremse, Klimaanlage etc.) Nischenentwicklungsprojekte (z.B. Spurwechsel- und Zahnradbahndrehgestelle, People Mover- oder Magnetschwebesysteme etc.) Kompetenzen im Bereich strukturelles Kleben und [&hellip;]","og_url":"https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/","og_site_name":"PROSE - Shaping tomorrow\u2019s mobility","article_published_time":"2023-10-23T13:58:00+00:00","article_modified_time":"2023-11-24T12:19:11+00:00","og_image":[{"width":922,"height":698,"url":"https:\/\/prose.one\/wp-content\/uploads\/MicrosoftTeams-image-32.png","type":"image\/png"}],"author":"Prose","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Prose","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/#article","isPartOf":{"@id":"https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/"},"author":{"name":"Prose","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9"},"headline":"Mechanische Konstruktion und Systemintegration","datePublished":"2023-10-23T13:58:00+00:00","dateModified":"2023-11-24T12:19:11+00:00","mainEntityOfPage":{"@id":"https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/"},"wordCount":196,"publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"image":{"@id":"https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/MicrosoftTeams-image-32.png","keywords":["Mechanische Fahrzeug- &amp; Systemtechnik","Modernisierung","Pr\u00fcfst\u00e4nde","Technische Dokumentation"],"articleSection":["Ausgew\u00e4hlte Projekte","Ihr Schienenfahrzeug bauen","Ihre Flotte fit machen","Innovation der Mobilit\u00e4t von morgen","Kategorien Referenzen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/","url":"https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/","name":"Mechanische Konstruktion und Systemintegration - PROSE - Shaping tomorrow\u2019s mobility","isPartOf":{"@id":"https:\/\/prose.one\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/#primaryimage"},"image":{"@id":"https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/MicrosoftTeams-image-32.png","datePublished":"2023-10-23T13:58:00+00:00","dateModified":"2023-11-24T12:19:11+00:00","breadcrumb":{"@id":"https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/#primaryimage","url":"https:\/\/prose.one\/wp-content\/uploads\/MicrosoftTeams-image-32.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/MicrosoftTeams-image-32.png","width":922,"height":698},{"@type":"BreadcrumbList","@id":"https:\/\/prose.one\/de\/mechanische-konstruktion-und-system-integration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/prose.one\/de\/"},{"@type":"ListItem","position":2,"name":"Mechanische Konstruktion und Systemintegration"}]},{"@type":"WebSite","@id":"https:\/\/prose.one\/de\/#website","url":"https:\/\/prose.one\/de\/","name":"PROSE Shaping tomorrow\u2019s mobility","description":"Shaping tomorrow\u2019s mobility","publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prose.one\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/prose.one\/de\/#organization","name":"PROSE","url":"https:\/\/prose.one\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/","url":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","width":1182,"height":326,"caption":"PROSE"},"image":{"@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/prose-group"]},{"@type":"Person","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9","name":"Prose","url":"https:\/\/prose.one\/de\/author\/adminprose\/"}]}},"_links":{"self":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/9115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/comments?post=9115"}],"version-history":[{"count":4,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/9115\/revisions"}],"predecessor-version":[{"id":9406,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/9115\/revisions\/9406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media\/9405"}],"wp:attachment":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media?parent=9115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/categories?post=9115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/tags?post=9115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}