{"id":8487,"date":"2023-04-10T13:46:56","date_gmt":"2023-04-10T12:46:56","guid":{"rendered":"https:\/\/prose.one\/technical-documentation-in-the-sj-x2000-refurbishment-project\/"},"modified":"2023-09-12T15:31:41","modified_gmt":"2023-09-12T14:31:41","slug":"technische-dokumentation-im-sanierungsprojekt-sj-x2000","status":"publish","type":"post","link":"https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/","title":{"rendered":"Technische Dokumentation im  Sanierungsprojekt SJ X2000"},"content":{"rendered":"<h3 class=\"detail\">Kunde: SJ AB, Schweden<\/h3>\n<h4>Projektaufgaben<\/h4>\n<ul>\n<li>Technische Dokumentation<\/li>\n<li>\u00dcbersetzung<\/li>\n<li>Koordination<\/li>\n<li>\u00dcberpr\u00fcfung<\/li>\n<\/ul>\n<h4>Unsere Umsetzung<\/h4>\n<p>PROSE trug mit seiner Hilfe bei der Erstellung neuer technischer Dokumente f\u00fcr die modernisierte Zugflotte sowie bei der \u00dcbersetzung, Koordination und internen \u00dcberpr\u00fcfung zu dem Projekt bei. Rund 400 Dokumente wurden f\u00fcr das Projekt erstellt und anschlie\u00dfend vom Kunden gepr\u00fcft. Das Team aus technischen Redakteuren von PROSE leistete seinen Beitrag bei der Aktualisierung und Erstellung neuer Inhalte von Systemhandb\u00fcchern, Wartungshandb\u00fcchern, Ersatzteilkatalogen, Anleitungen zur Fehlerbehebung, Diagnosedatenbl\u00e4ttern (DDS-Listen), Komponentenbl\u00e4ttern, Schulungsunterlagen etc.<\/p>\n<h4>Kundennutzen<\/h4>\n<p>PROSE unterst\u00fctzte ABB und Stadler bei der Erstellung und \u00dcbersetzung der neuen technischen Dokumentation f\u00fcr SJ. Die Dokumentation wurde im B\u00fcro erstellt und mit der Arbeit im Depot kombiniert, um sicherzustellen, dass jedes Produkt\/jede Funktion klar beschrieben war. Dies hilft den Betreibern, die aktualisierten Produkte und Systeme zu verstehen, gew\u00e4hrleistet die korrekte Verwendung der Produkte und garantiert Sicherheit bei den Wartungsarbeiten.<\/p>\n<p><a href=\"https:\/\/prose.one\/de\/alle-unsere-dienstleistungen\/\"><img decoding=\"async\" class=\"alignnone wp-image-7590\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Modernisierung-Modernisation.svg\" alt=\"\" width=\"155\" \/><\/a> <a href=\"https:\/\/prose.one\/de\/alle-unsere-dienstleistungen\/\"><img decoding=\"async\" class=\"alignnone wp-image-7608\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Technische-Dokumentation-Documentation-services.svg\" alt=\"\" width=\"155\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kunde: SJ AB, Schweden Projektaufgaben Technische Dokumentation \u00dcbersetzung Koordination \u00dcberpr\u00fcfung Unsere Umsetzung PROSE trug mit seiner Hilfe bei der Erstellung neuer technischer Dokumente f\u00fcr die modernisierte Zugflotte sowie bei der \u00dcbersetzung, Koordination und internen \u00dcberpr\u00fcfung zu dem Projekt bei. Rund 400 Dokumente wurden f\u00fcr das Projekt erstellt und anschlie\u00dfend vom Kunden gepr\u00fcft. Das Team aus [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6887,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[138,136,135,130],"tags":[171,120],"class_list":["post-8487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ausgewahlte-projekte","category-ihr-team-starken","category-ihre-flotte-fit-machen","category-categories-referenzen","tag-modernisierung","tag-technische-dokumentation-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Technische Dokumentation im Sanierungsprojekt SJ X2000 - PROSE - Shaping tomorrow\u2019s mobility<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Technische Dokumentation im Sanierungsprojekt SJ X2000 - PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"og:description\" content=\"Kunde: SJ AB, Schweden Projektaufgaben Technische Dokumentation \u00dcbersetzung Koordination \u00dcberpr\u00fcfung Unsere Umsetzung PROSE trug mit seiner Hilfe bei der Erstellung neuer technischer Dokumente f\u00fcr die modernisierte Zugflotte sowie bei der \u00dcbersetzung, Koordination und internen \u00dcberpr\u00fcfung zu dem Projekt bei. Rund 400 Dokumente wurden f\u00fcr das Projekt erstellt und anschlie\u00dfend vom Kunden gepr\u00fcft. Das Team aus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/\" \/>\n<meta property=\"og:site_name\" content=\"PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-10T12:46:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-12T14:31:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prose.one\/wp-content\/uploads\/Bild20.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Prose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prose\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\\\/\"},\"author\":{\"name\":\"Prose\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\"},\"headline\":\"Technische Dokumentation im Sanierungsprojekt SJ X2000\",\"datePublished\":\"2023-04-10T12:46:56+00:00\",\"dateModified\":\"2023-09-12T14:31:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\\\/\"},\"wordCount\":163,\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/Bild20.png\",\"keywords\":[\"Modernisierung\",\"Technische Dokumentation\"],\"articleSection\":[\"Ausgew\u00e4hlte Projekte\",\"Ihr Team st\u00e4rken\",\"Ihre Flotte fit machen\",\"Kategorien Referenzen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\\\/\",\"name\":\"Technische Dokumentation im Sanierungsprojekt SJ X2000 - PROSE - Shaping tomorrow\u2019s mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/Bild20.png\",\"datePublished\":\"2023-04-10T12:46:56+00:00\",\"dateModified\":\"2023-09-12T14:31:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prose.one\\\/de\\\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/Bild20.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/Bild20.png\",\"width\":2000,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/prose.one\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Technische Dokumentation im Sanierungsprojekt SJ X2000\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"name\":\"PROSE Shaping tomorrow\u2019s mobility\",\"description\":\"Shaping tomorrow\u2019s mobility\",\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prose.one\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\",\"name\":\"PROSE\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"width\":1182,\"height\":326,\"caption\":\"PROSE\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prose-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\",\"name\":\"Prose\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/author\\\/adminprose\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Technische Dokumentation im Sanierungsprojekt SJ X2000 - PROSE - Shaping tomorrow\u2019s mobility","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/","og_locale":"de_DE","og_type":"article","og_title":"Technische Dokumentation im Sanierungsprojekt SJ X2000 - PROSE - Shaping tomorrow\u2019s mobility","og_description":"Kunde: SJ AB, Schweden Projektaufgaben Technische Dokumentation \u00dcbersetzung Koordination \u00dcberpr\u00fcfung Unsere Umsetzung PROSE trug mit seiner Hilfe bei der Erstellung neuer technischer Dokumente f\u00fcr die modernisierte Zugflotte sowie bei der \u00dcbersetzung, Koordination und internen \u00dcberpr\u00fcfung zu dem Projekt bei. Rund 400 Dokumente wurden f\u00fcr das Projekt erstellt und anschlie\u00dfend vom Kunden gepr\u00fcft. Das Team aus [&hellip;]","og_url":"https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/","og_site_name":"PROSE - Shaping tomorrow\u2019s mobility","article_published_time":"2023-04-10T12:46:56+00:00","article_modified_time":"2023-09-12T14:31:41+00:00","og_image":[{"width":2000,"height":1500,"url":"https:\/\/prose.one\/wp-content\/uploads\/Bild20.png","type":"image\/png"}],"author":"Prose","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Prose","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/#article","isPartOf":{"@id":"https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/"},"author":{"name":"Prose","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9"},"headline":"Technische Dokumentation im Sanierungsprojekt SJ X2000","datePublished":"2023-04-10T12:46:56+00:00","dateModified":"2023-09-12T14:31:41+00:00","mainEntityOfPage":{"@id":"https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/"},"wordCount":163,"publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"image":{"@id":"https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/Bild20.png","keywords":["Modernisierung","Technische Dokumentation"],"articleSection":["Ausgew\u00e4hlte Projekte","Ihr Team st\u00e4rken","Ihre Flotte fit machen","Kategorien Referenzen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/","url":"https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/","name":"Technische Dokumentation im Sanierungsprojekt SJ X2000 - PROSE - Shaping tomorrow\u2019s mobility","isPartOf":{"@id":"https:\/\/prose.one\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/#primaryimage"},"image":{"@id":"https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/Bild20.png","datePublished":"2023-04-10T12:46:56+00:00","dateModified":"2023-09-12T14:31:41+00:00","breadcrumb":{"@id":"https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/#primaryimage","url":"https:\/\/prose.one\/wp-content\/uploads\/Bild20.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/Bild20.png","width":2000,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/prose.one\/de\/technische-dokumentation-im-sanierungsprojekt-sj-x2000\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/prose.one\/de\/"},{"@type":"ListItem","position":2,"name":"Technische Dokumentation im Sanierungsprojekt SJ X2000"}]},{"@type":"WebSite","@id":"https:\/\/prose.one\/de\/#website","url":"https:\/\/prose.one\/de\/","name":"PROSE Shaping tomorrow\u2019s mobility","description":"Shaping tomorrow\u2019s mobility","publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prose.one\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/prose.one\/de\/#organization","name":"PROSE","url":"https:\/\/prose.one\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/","url":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","width":1182,"height":326,"caption":"PROSE"},"image":{"@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/prose-group"]},{"@type":"Person","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9","name":"Prose","url":"https:\/\/prose.one\/de\/author\/adminprose\/"}]}},"_links":{"self":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/8487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/comments?post=8487"}],"version-history":[{"count":2,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/8487\/revisions"}],"predecessor-version":[{"id":8489,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/8487\/revisions\/8489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media\/6887"}],"wp:attachment":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media?parent=8487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/categories?post=8487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/tags?post=8487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}