{"id":8414,"date":"2023-04-10T10:08:24","date_gmt":"2023-04-10T09:08:24","guid":{"rendered":"https:\/\/prose.one\/development-of-a-gauge-changing-facility-for-operator-mob\/"},"modified":"2023-09-12T12:53:20","modified_gmt":"2023-09-12T11:53:20","slug":"entwicklung-einer-umspuranlage-fuer-den-betreiber-mob","status":"publish","type":"post","link":"https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/","title":{"rendered":"Entwicklung einer Umspuranlage f\u00fcr den Betreiber MOB"},"content":{"rendered":"<h3 class=\"detail\">Kunde: Chemin de fer Montreux Oberland bernois MOB, Schweiz<\/h3>\n<h4>Projektaufgaben<\/h4>\n<ul>\n<li>Machbarkeitsanalyse<\/li>\n<li>Mechanische und steuerungstechnische Entwicklung<\/li>\n<li>Ausf\u00fchrliche Fertigungskonstruktion<\/li>\n<li>Festigkeitsanalyse<\/li>\n<li>Unterst\u00fctzung Zulassung<\/li>\n<\/ul>\n<h4>Unsere Umsetzung<\/h4>\n<p>In Zusammenarbeit mit MOB hat PROSE die Umspuranlage in mehreren Phasen vom einfachen Prototypaufbau zur komplexen Serienanlage weiterentwickelt.<\/p>\n<h4>Kundennutzen<\/h4>\n<p>Bereits ab einem fr\u00fchen Stadium der Entwicklung der Umspuranlage hat PROSE MOB bei Zulassungsthemen unterst\u00fctzt. Die Komplexit\u00e4t der vielz\u00e4hligen Schnittstellen zwischen der Umspuranlage und den Fahrzeugen, der Infrastruktur sowie den Zugsicherungen von MOB und BLS wurde von PROSE \u00fcber eine enge Zusammenarbeit mit den beteiligten Partnern ber\u00fccksichtigt. Von der Konzeptionierung bis zur erfolgreichen Inbetriebnahme konnte MOB l\u00f6sungsorientiert und zielgerichtet aus einer Hand unterst\u00fctzt werden.<\/p>\n<p><a href=\"https:\/\/prose.one\/de\/alle-unsere-dienstleistungen\/\"><img decoding=\"async\" class=\"alignnone wp-image-7588\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Mechanische-Fahrzeug-Systemtechnik-Mechanical-vehicle-systems-engineering.svg\" alt=\"\" width=\"155\" \/><\/a> <a href=\"https:\/\/prose.one\/de\/alle-unsere-dienstleistungen\/\"><img decoding=\"async\" class=\"alignnone wp-image-7584\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Elektrotechnik-Elektronik-Electrial-electronic-engineering.svg\" alt=\"\" width=\"155\" \/><\/a> <a href=\"https:\/\/prose.one\/de\/alle-unsere-dienstleistungen\/\"><img decoding=\"async\" class=\"alignnone wp-image-4811\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Software-1.svg\" alt=\"\" width=\"155\" height=\"709\" \/><\/a> <a href=\"https:\/\/prose.one\/de\/alle-unsere-dienstleistungen\/\"><img decoding=\"async\" class=\"alignnone wp-image-7612\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Validierung-Verifizierung-Validation-Verification.svg\" alt=\"\" width=\"155\" \/><\/a> <a href=\"https:\/\/prose.one\/de\/alle-unsere-dienstleistungen\/\"><img decoding=\"async\" class=\"alignnone wp-image-4809\" src=\"https:\/\/prose.one\/wp-content\/uploads\/RAMS-LCC-1.svg\" alt=\"\" width=\"155\" height=\"709\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kunde: Chemin de fer Montreux Oberland bernois MOB, Schweiz Projektaufgaben Machbarkeitsanalyse Mechanische und steuerungstechnische Entwicklung Ausf\u00fchrliche Fertigungskonstruktion Festigkeitsanalyse Unterst\u00fctzung Zulassung Unsere Umsetzung In Zusammenarbeit mit MOB hat PROSE die Umspuranlage in mehreren Phasen vom einfachen Prototypaufbau zur komplexen Serienanlage weiterentwickelt. Kundennutzen Bereits ab einem fr\u00fchen Stadium der Entwicklung der Umspuranlage hat PROSE MOB bei Zulassungsthemen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6873,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[138,132,134,130],"tags":[163,170,176,181,186],"class_list":["post-8414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ausgewahlte-projekte","category-ihr-schienenfahrzeug-bauen","category-innovation-der-mobilitat-von-morgen","category-categories-referenzen","tag-elektrotechnik","tag-mechanische-fahrzeug-systemtechnik","tag-rams-lcc","tag-software-de","tag-validierung-verifizierung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entwicklung einer Umspuranlage f\u00fcr den Betreiber MOB - PROSE - Shaping tomorrow\u2019s mobility<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entwicklung einer Umspuranlage f\u00fcr den Betreiber MOB - PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"og:description\" content=\"Kunde: Chemin de fer Montreux Oberland bernois MOB, Schweiz Projektaufgaben Machbarkeitsanalyse Mechanische und steuerungstechnische Entwicklung Ausf\u00fchrliche Fertigungskonstruktion Festigkeitsanalyse Unterst\u00fctzung Zulassung Unsere Umsetzung In Zusammenarbeit mit MOB hat PROSE die Umspuranlage in mehreren Phasen vom einfachen Prototypaufbau zur komplexen Serienanlage weiterentwickelt. Kundennutzen Bereits ab einem fr\u00fchen Stadium der Entwicklung der Umspuranlage hat PROSE MOB bei Zulassungsthemen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/\" \/>\n<meta property=\"og:site_name\" content=\"PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-10T09:08:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-12T11:53:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prose.one\/wp-content\/uploads\/Bild12.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Prose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prose\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\\\/\"},\"author\":{\"name\":\"Prose\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\"},\"headline\":\"Entwicklung einer Umspuranlage f\u00fcr den Betreiber MOB\",\"datePublished\":\"2023-04-10T09:08:24+00:00\",\"dateModified\":\"2023-09-12T11:53:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\\\/\"},\"wordCount\":122,\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/Bild12.png\",\"keywords\":[\"Elektrotechnik\",\"Mechanische Fahrzeug- &amp; Systemtechnik\",\"RAMS &amp; LCC\",\"Software\",\"Validierung &amp; Verifizierung\"],\"articleSection\":[\"Ausgew\u00e4hlte Projekte\",\"Ihr Schienenfahrzeug bauen\",\"Innovation der Mobilit\u00e4t von morgen\",\"Kategorien Referenzen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\\\/\",\"name\":\"Entwicklung einer Umspuranlage f\u00fcr den Betreiber MOB - PROSE - Shaping tomorrow\u2019s mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/Bild12.png\",\"datePublished\":\"2023-04-10T09:08:24+00:00\",\"dateModified\":\"2023-09-12T11:53:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prose.one\\\/de\\\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/Bild12.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/Bild12.png\",\"width\":2000,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/prose.one\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entwicklung einer Umspuranlage f\u00fcr den Betreiber MOB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"name\":\"PROSE Shaping tomorrow\u2019s mobility\",\"description\":\"Shaping tomorrow\u2019s mobility\",\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prose.one\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\",\"name\":\"PROSE\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"width\":1182,\"height\":326,\"caption\":\"PROSE\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prose-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\",\"name\":\"Prose\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/author\\\/adminprose\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entwicklung einer Umspuranlage f\u00fcr den Betreiber MOB - PROSE - Shaping tomorrow\u2019s mobility","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/","og_locale":"de_DE","og_type":"article","og_title":"Entwicklung einer Umspuranlage f\u00fcr den Betreiber MOB - PROSE - Shaping tomorrow\u2019s mobility","og_description":"Kunde: Chemin de fer Montreux Oberland bernois MOB, Schweiz Projektaufgaben Machbarkeitsanalyse Mechanische und steuerungstechnische Entwicklung Ausf\u00fchrliche Fertigungskonstruktion Festigkeitsanalyse Unterst\u00fctzung Zulassung Unsere Umsetzung In Zusammenarbeit mit MOB hat PROSE die Umspuranlage in mehreren Phasen vom einfachen Prototypaufbau zur komplexen Serienanlage weiterentwickelt. Kundennutzen Bereits ab einem fr\u00fchen Stadium der Entwicklung der Umspuranlage hat PROSE MOB bei Zulassungsthemen [&hellip;]","og_url":"https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/","og_site_name":"PROSE - Shaping tomorrow\u2019s mobility","article_published_time":"2023-04-10T09:08:24+00:00","article_modified_time":"2023-09-12T11:53:20+00:00","og_image":[{"url":"https:\/\/prose.one\/wp-content\/uploads\/Bild12.png","width":2000,"height":1500,"type":"image\/png"}],"author":"Prose","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Prose","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/#article","isPartOf":{"@id":"https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/"},"author":{"name":"Prose","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9"},"headline":"Entwicklung einer Umspuranlage f\u00fcr den Betreiber MOB","datePublished":"2023-04-10T09:08:24+00:00","dateModified":"2023-09-12T11:53:20+00:00","mainEntityOfPage":{"@id":"https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/"},"wordCount":122,"publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"image":{"@id":"https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/Bild12.png","keywords":["Elektrotechnik","Mechanische Fahrzeug- &amp; Systemtechnik","RAMS &amp; LCC","Software","Validierung &amp; Verifizierung"],"articleSection":["Ausgew\u00e4hlte Projekte","Ihr Schienenfahrzeug bauen","Innovation der Mobilit\u00e4t von morgen","Kategorien Referenzen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/","url":"https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/","name":"Entwicklung einer Umspuranlage f\u00fcr den Betreiber MOB - PROSE - Shaping tomorrow\u2019s mobility","isPartOf":{"@id":"https:\/\/prose.one\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/#primaryimage"},"image":{"@id":"https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/Bild12.png","datePublished":"2023-04-10T09:08:24+00:00","dateModified":"2023-09-12T11:53:20+00:00","breadcrumb":{"@id":"https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/#primaryimage","url":"https:\/\/prose.one\/wp-content\/uploads\/Bild12.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/Bild12.png","width":2000,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/prose.one\/de\/entwicklung-einer-umspuranlage-fuer-den-betreiber-mob\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/prose.one\/de\/"},{"@type":"ListItem","position":2,"name":"Entwicklung einer Umspuranlage f\u00fcr den Betreiber MOB"}]},{"@type":"WebSite","@id":"https:\/\/prose.one\/de\/#website","url":"https:\/\/prose.one\/de\/","name":"PROSE Shaping tomorrow\u2019s mobility","description":"Shaping tomorrow\u2019s mobility","publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prose.one\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/prose.one\/de\/#organization","name":"PROSE","url":"https:\/\/prose.one\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/","url":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","width":1182,"height":326,"caption":"PROSE"},"image":{"@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/prose-group"]},{"@type":"Person","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9","name":"Prose","url":"https:\/\/prose.one\/de\/author\/adminprose\/"}]}},"_links":{"self":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/8414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/comments?post=8414"}],"version-history":[{"count":2,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/8414\/revisions"}],"predecessor-version":[{"id":8416,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/8414\/revisions\/8416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media\/6873"}],"wp:attachment":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media?parent=8414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/categories?post=8414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/tags?post=8414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}