{"id":8143,"date":"2023-03-16T11:09:57","date_gmt":"2023-03-16T10:09:57","guid":{"rendered":"https:\/\/prose.one\/zps-vehicle-expert-for-the-electronic-network-saar-rb\/"},"modified":"2025-09-25T10:31:47","modified_gmt":"2025-09-25T09:31:47","slug":"zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb","status":"publish","type":"post","link":"https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/","title":{"rendered":"ZPS-Fahrzeugexperte f\u00fcr das elektrische Netzwerk &#8222;Saar-RB&#8220;"},"content":{"rendered":"<h3 class=\"detail\">Kunde: ZPS &#8211; Zweckverband Personennahverkehr Saarland, Deutschland;<br \/>\nSPNV Nord &#8211; Zweckverband Schienenpersonennahverkehr Rheinland-Pfalz Nord,Deutschland;<br \/>\nSPNV S\u00fcd &#8211; Zweckverband Schienenpersonennahverkehr Rheinland-Pfalz S\u00fcd, Deutschland<\/h3>\n<h4>Projektaufgaben<\/h4>\n<ul>\n<li>Bewertung der funktionalen Anforderungen, der Qualit\u00e4t und des Zeitplans<\/li>\n<li>Entwicklung von technischen L\u00f6sungen<\/li>\n<li>Aufbau und Pflege eines Fahrzeuginformationssystems<\/li>\n<li>Technische Beratung im Rahmen der Kontrollgruppe<\/li>\n<\/ul>\n<h4>Unsere Umsetzung<\/h4>\n<p>Zun\u00e4chst wurde eine Bewertung der funktionalen Anforderungen, des Qualit\u00e4tssicherungsplans und des Zeitplans f\u00fcr die Lieferung durchgef\u00fchrt. Dann wurden die Anforderungen an das Asset-Management und Berichtssystem gesammelt. Das System wurde ausgeschrieben und bewertet, und es wurde ein geeigneter Lieferant ausgew\u00e4hlt. Zusammen mit der Inbetriebnahme des Asset-Management- und Berichterstattungssystems wurde die Kontrollgruppe, die die Entwicklung, Herstellung und Inbetriebnahme sowie die Wartung der Fahrzeuge \u00fcberwacht, in Betrieb genommen, um den langfristigen Wert der Anlagen zu gew\u00e4hrleisten.<\/p>\n<h4>Kundennutzen<\/h4>\n<p>Geringeres Risiko f\u00fcr die zust\u00e4ndige Beh\u00f6rde bei der Beschaffung der Fahrzeuge.<br \/>\nDie Beh\u00f6rde kann dank der von PROSE entwickelten technischen L\u00f6sungen richtige und gezielte Entscheidungen treffen.<\/p>\n<p><a href=\"https:\/\/prose.one\/de\/alle-unsere-dienstleistungen\/\"><img decoding=\"async\" class=\"alignnone wp-image-7582\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Beschaffungsmanagement-Procurement-Management.svg\" alt=\"\" width=\"155\" \/><\/a>\u00a0 <a href=\"https:\/\/prose.one\/de\/alle-unsere-dienstleistungen\/\"><img decoding=\"async\" class=\"alignnone wp-image-7616\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Instandhaltungsunterstutzung-optimierung-Maintenance-support-and-optimisation-1.svg\" alt=\"\" width=\"155\" \/><\/a>\u00a0 <a href=\"https:\/\/prose.one\/de\/alle-unsere-dienstleistungen\/\"><img decoding=\"async\" class=\"alignnone wp-image-7614\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Zulassungsmanagement-vehicle-authorisation.svg\" alt=\"\" width=\"155\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kunde: ZPS &#8211; Zweckverband Personennahverkehr Saarland, Deutschland; SPNV Nord &#8211; Zweckverband Schienenpersonennahverkehr Rheinland-Pfalz Nord,Deutschland; SPNV S\u00fcd &#8211; Zweckverband Schienenpersonennahverkehr Rheinland-Pfalz S\u00fcd, Deutschland Projektaufgaben Bewertung der funktionalen Anforderungen, der Qualit\u00e4t und des Zeitplans Entwicklung von technischen L\u00f6sungen Aufbau und Pflege eines Fahrzeuginformationssystems Technische Beratung im Rahmen der Kontrollgruppe Unsere Umsetzung Zun\u00e4chst wurde eine Bewertung der funktionalen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7414,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[137,139,132,136,135,131,134],"tags":[173,190,187],"class_list":["post-8143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-das-bahnsystem-beherrschen","category-dienstleistungen-a-z","category-ihr-schienenfahrzeug-bauen","category-ihr-team-starken","category-ihre-flotte-fit-machen","category-ihre-strategie-entwickeln","category-innovation-der-mobilitat-von-morgen","tag-beschaffungsmanagement","tag-instandhaltungsunterstutzung-optimierung","tag-zulassungsmanagement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ZPS-Fahrzeugexperte f\u00fcr das elektrische Netzwerk &quot;Saar-RB&quot; - PROSE - Shaping tomorrow\u2019s mobility<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZPS-Fahrzeugexperte f\u00fcr das elektrische Netzwerk &quot;Saar-RB&quot; - PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"og:description\" content=\"Kunde: ZPS &#8211; Zweckverband Personennahverkehr Saarland, Deutschland; SPNV Nord &#8211; Zweckverband Schienenpersonennahverkehr Rheinland-Pfalz Nord,Deutschland; SPNV S\u00fcd &#8211; Zweckverband Schienenpersonennahverkehr Rheinland-Pfalz S\u00fcd, Deutschland Projektaufgaben Bewertung der funktionalen Anforderungen, der Qualit\u00e4t und des Zeitplans Entwicklung von technischen L\u00f6sungen Aufbau und Pflege eines Fahrzeuginformationssystems Technische Beratung im Rahmen der Kontrollgruppe Unsere Umsetzung Zun\u00e4chst wurde eine Bewertung der funktionalen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/\" \/>\n<meta property=\"og:site_name\" content=\"PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-16T10:09:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-25T09:31:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prose.one\/wp-content\/uploads\/ZPS-vehicle-expert-for-the-electronic-network-Saar-RB.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1501\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"O K\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"O K\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\\\/\"},\"author\":{\"name\":\"O K\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/9d7de22b0145cc7a7469e0b437cb6e04\"},\"headline\":\"ZPS-Fahrzeugexperte f\u00fcr das elektrische Netzwerk &#8222;Saar-RB&#8220;\",\"datePublished\":\"2023-03-16T10:09:57+00:00\",\"dateModified\":\"2025-09-25T09:31:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\\\/\"},\"wordCount\":172,\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/ZPS-vehicle-expert-for-the-electronic-network-Saar-RB.png\",\"keywords\":[\"Beschaffungsmanagement\",\"Instandhaltungsunterst\u00fctzung &amp; -optimierung\",\"Zulassungsmanagement\"],\"articleSection\":[\"Das Bahnsystem beherrschen\",\"Dienstleistungen A-Z\",\"Ihr Schienenfahrzeug bauen\",\"Ihr Team st\u00e4rken\",\"Ihre Flotte fit machen\",\"Ihre Strategie entwickeln\",\"Innovation der Mobilit\u00e4t von morgen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\\\/\",\"name\":\"ZPS-Fahrzeugexperte f\u00fcr das elektrische Netzwerk \\\"Saar-RB\\\" - PROSE - Shaping tomorrow\u2019s mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/ZPS-vehicle-expert-for-the-electronic-network-Saar-RB.png\",\"datePublished\":\"2023-03-16T10:09:57+00:00\",\"dateModified\":\"2025-09-25T09:31:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prose.one\\\/de\\\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/ZPS-vehicle-expert-for-the-electronic-network-Saar-RB.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/ZPS-vehicle-expert-for-the-electronic-network-Saar-RB.png\",\"width\":2000,\"height\":1501},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/prose.one\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ZPS-Fahrzeugexperte f\u00fcr das elektrische Netzwerk &#8220;Saar-RB&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"name\":\"PROSE Shaping tomorrow\u2019s mobility\",\"description\":\"Shaping tomorrow\u2019s mobility\",\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prose.one\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\",\"name\":\"PROSE\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"width\":1182,\"height\":326,\"caption\":\"PROSE\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prose-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/9d7de22b0145cc7a7469e0b437cb6e04\",\"name\":\"O K\",\"sameAs\":[\"https:\\\/\\\/www.odd.se\"],\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/author\\\/adminodd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZPS-Fahrzeugexperte f\u00fcr das elektrische Netzwerk \"Saar-RB\" - PROSE - Shaping tomorrow\u2019s mobility","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/","og_locale":"de_DE","og_type":"article","og_title":"ZPS-Fahrzeugexperte f\u00fcr das elektrische Netzwerk \"Saar-RB\" - PROSE - Shaping tomorrow\u2019s mobility","og_description":"Kunde: ZPS &#8211; Zweckverband Personennahverkehr Saarland, Deutschland; SPNV Nord &#8211; Zweckverband Schienenpersonennahverkehr Rheinland-Pfalz Nord,Deutschland; SPNV S\u00fcd &#8211; Zweckverband Schienenpersonennahverkehr Rheinland-Pfalz S\u00fcd, Deutschland Projektaufgaben Bewertung der funktionalen Anforderungen, der Qualit\u00e4t und des Zeitplans Entwicklung von technischen L\u00f6sungen Aufbau und Pflege eines Fahrzeuginformationssystems Technische Beratung im Rahmen der Kontrollgruppe Unsere Umsetzung Zun\u00e4chst wurde eine Bewertung der funktionalen [&hellip;]","og_url":"https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/","og_site_name":"PROSE - Shaping tomorrow\u2019s mobility","article_published_time":"2023-03-16T10:09:57+00:00","article_modified_time":"2025-09-25T09:31:47+00:00","og_image":[{"width":2000,"height":1501,"url":"https:\/\/prose.one\/wp-content\/uploads\/ZPS-vehicle-expert-for-the-electronic-network-Saar-RB.png","type":"image\/png"}],"author":"O K","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"O K","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/#article","isPartOf":{"@id":"https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/"},"author":{"name":"O K","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/9d7de22b0145cc7a7469e0b437cb6e04"},"headline":"ZPS-Fahrzeugexperte f\u00fcr das elektrische Netzwerk &#8222;Saar-RB&#8220;","datePublished":"2023-03-16T10:09:57+00:00","dateModified":"2025-09-25T09:31:47+00:00","mainEntityOfPage":{"@id":"https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/"},"wordCount":172,"publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"image":{"@id":"https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/ZPS-vehicle-expert-for-the-electronic-network-Saar-RB.png","keywords":["Beschaffungsmanagement","Instandhaltungsunterst\u00fctzung &amp; -optimierung","Zulassungsmanagement"],"articleSection":["Das Bahnsystem beherrschen","Dienstleistungen A-Z","Ihr Schienenfahrzeug bauen","Ihr Team st\u00e4rken","Ihre Flotte fit machen","Ihre Strategie entwickeln","Innovation der Mobilit\u00e4t von morgen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/","url":"https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/","name":"ZPS-Fahrzeugexperte f\u00fcr das elektrische Netzwerk \"Saar-RB\" - PROSE - Shaping tomorrow\u2019s mobility","isPartOf":{"@id":"https:\/\/prose.one\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/#primaryimage"},"image":{"@id":"https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/ZPS-vehicle-expert-for-the-electronic-network-Saar-RB.png","datePublished":"2023-03-16T10:09:57+00:00","dateModified":"2025-09-25T09:31:47+00:00","breadcrumb":{"@id":"https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/#primaryimage","url":"https:\/\/prose.one\/wp-content\/uploads\/ZPS-vehicle-expert-for-the-electronic-network-Saar-RB.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/ZPS-vehicle-expert-for-the-electronic-network-Saar-RB.png","width":2000,"height":1501},{"@type":"BreadcrumbList","@id":"https:\/\/prose.one\/de\/zps-fahrzeugexperte-fuer-das-elektronische-netzwerk-saar-rb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/prose.one\/de\/"},{"@type":"ListItem","position":2,"name":"ZPS-Fahrzeugexperte f\u00fcr das elektrische Netzwerk &#8220;Saar-RB&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/prose.one\/de\/#website","url":"https:\/\/prose.one\/de\/","name":"PROSE Shaping tomorrow\u2019s mobility","description":"Shaping tomorrow\u2019s mobility","publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prose.one\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/prose.one\/de\/#organization","name":"PROSE","url":"https:\/\/prose.one\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/","url":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","width":1182,"height":326,"caption":"PROSE"},"image":{"@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/prose-group"]},{"@type":"Person","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/9d7de22b0145cc7a7469e0b437cb6e04","name":"O K","sameAs":["https:\/\/www.odd.se"],"url":"https:\/\/prose.one\/de\/author\/adminodd\/"}]}},"_links":{"self":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/8143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/comments?post=8143"}],"version-history":[{"count":5,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/8143\/revisions"}],"predecessor-version":[{"id":12148,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/8143\/revisions\/12148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media\/7414"}],"wp:attachment":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media?parent=8143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/categories?post=8143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/tags?post=8143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}