{"id":8017,"date":"2023-04-28T10:07:38","date_gmt":"2023-04-28T09:07:38","guid":{"rendered":"https:\/\/prose.one\/prose-sweden-at-trainrail-recap\/"},"modified":"2023-09-06T08:38:29","modified_gmt":"2023-09-06T07:38:29","slug":"prose-schweden-bei-trainrail-recap","status":"publish","type":"post","link":"https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/","title":{"rendered":"PROSE-Schweden bei Train&#038;Rail \u2013 Recap"},"content":{"rendered":"<p>Ein herzliches Dankesch\u00f6n an alle, die uns diese Woche auf der Eisenbahnmesse in Stockholm besucht haben.<\/p>\n<p>Es war interessant, an der allerersten Initiative einer Messe speziell f\u00fcr das Rollmaterial in Stockholm teilzunehmen. Es gab viele relevante AusstellerInnen sowie wichtige Gespr\u00e4che. <\/p>\n<p>Wir sind gespannt auf das Ergebnis. Wir sind \u00fcberzeugt, dass eine Menge cooler und interessanter neuer Projekte anstehen. Bleiben Sie dran, um mehr zu erfahren.<\/p>\n<p>Wenn Sie die gestrige Pr\u00e4sentation unseres Dokumentationssystems verpasst haben, wenden Sie sich bitte an Amanda unter <a href=\"mailto:amanda.werner@prose.one\">amanda.werner@prose.one.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein herzliches Dankesch\u00f6n an alle, die uns diese Woche auf der Eisenbahnmesse in Stockholm besucht haben. Es war interessant, an der allerersten Initiative einer Messe speziell f\u00fcr das Rollmaterial in Stockholm teilzunehmen. Es gab viele relevante AusstellerInnen sowie wichtige Gespr\u00e4che. Wir sind gespannt auf das Ergebnis. Wir sind \u00fcberzeugt, dass eine Menge cooler und interessanter [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6990,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117,129,145],"tags":[159,165],"class_list":["post-8017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-de","category-business-de","category-veranstaltungen","tag-business-de","tag-veranstaltungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PROSE-Schweden bei Train&amp;Rail \u2013 Recap - PROSE - Shaping tomorrow\u2019s mobility<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PROSE-Schweden bei Train&amp;Rail \u2013 Recap - PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"og:description\" content=\"Ein herzliches Dankesch\u00f6n an alle, die uns diese Woche auf der Eisenbahnmesse in Stockholm besucht haben. Es war interessant, an der allerersten Initiative einer Messe speziell f\u00fcr das Rollmaterial in Stockholm teilzunehmen. Es gab viele relevante AusstellerInnen sowie wichtige Gespr\u00e4che. Wir sind gespannt auf das Ergebnis. Wir sind \u00fcberzeugt, dass eine Menge cooler und interessanter [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/\" \/>\n<meta property=\"og:site_name\" content=\"PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-28T09:07:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-06T07:38:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prose.one\/wp-content\/uploads\/IMG_5776.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2250\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Prose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prose\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-schweden-bei-trainrail-recap\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-schweden-bei-trainrail-recap\\\/\"},\"author\":{\"name\":\"Prose\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\"},\"headline\":\"PROSE-Schweden bei Train&#038;Rail \u2013 Recap\",\"datePublished\":\"2023-04-28T09:07:38+00:00\",\"dateModified\":\"2023-09-06T07:38:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-schweden-bei-trainrail-recap\\\/\"},\"wordCount\":94,\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-schweden-bei-trainrail-recap\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/IMG_5776.png\",\"keywords\":[\"Business\",\"Veranstaltungen\"],\"articleSection\":[\"Alle News\",\"Business\",\"Veranstaltungen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-schweden-bei-trainrail-recap\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-schweden-bei-trainrail-recap\\\/\",\"name\":\"PROSE-Schweden bei Train&Rail \u2013 Recap - PROSE - Shaping tomorrow\u2019s mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-schweden-bei-trainrail-recap\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-schweden-bei-trainrail-recap\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/IMG_5776.png\",\"datePublished\":\"2023-04-28T09:07:38+00:00\",\"dateModified\":\"2023-09-06T07:38:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-schweden-bei-trainrail-recap\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prose.one\\\/de\\\/prose-schweden-bei-trainrail-recap\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-schweden-bei-trainrail-recap\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/IMG_5776.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/IMG_5776.png\",\"width\":2250,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-schweden-bei-trainrail-recap\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/prose.one\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROSE-Schweden bei Train&#038;Rail \u2013 Recap\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"name\":\"PROSE Shaping tomorrow\u2019s mobility\",\"description\":\"Shaping tomorrow\u2019s mobility\",\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prose.one\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\",\"name\":\"PROSE\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"width\":1182,\"height\":326,\"caption\":\"PROSE\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prose-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\",\"name\":\"Prose\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/author\\\/adminprose\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PROSE-Schweden bei Train&Rail \u2013 Recap - PROSE - Shaping tomorrow\u2019s mobility","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/","og_locale":"de_DE","og_type":"article","og_title":"PROSE-Schweden bei Train&Rail \u2013 Recap - PROSE - Shaping tomorrow\u2019s mobility","og_description":"Ein herzliches Dankesch\u00f6n an alle, die uns diese Woche auf der Eisenbahnmesse in Stockholm besucht haben. Es war interessant, an der allerersten Initiative einer Messe speziell f\u00fcr das Rollmaterial in Stockholm teilzunehmen. Es gab viele relevante AusstellerInnen sowie wichtige Gespr\u00e4che. Wir sind gespannt auf das Ergebnis. Wir sind \u00fcberzeugt, dass eine Menge cooler und interessanter [&hellip;]","og_url":"https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/","og_site_name":"PROSE - Shaping tomorrow\u2019s mobility","article_published_time":"2023-04-28T09:07:38+00:00","article_modified_time":"2023-09-06T07:38:29+00:00","og_image":[{"url":"https:\/\/prose.one\/wp-content\/uploads\/IMG_5776.png","width":2250,"height":1500,"type":"image\/png"}],"author":"Prose","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Prose","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/#article","isPartOf":{"@id":"https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/"},"author":{"name":"Prose","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9"},"headline":"PROSE-Schweden bei Train&#038;Rail \u2013 Recap","datePublished":"2023-04-28T09:07:38+00:00","dateModified":"2023-09-06T07:38:29+00:00","mainEntityOfPage":{"@id":"https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/"},"wordCount":94,"publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"image":{"@id":"https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/IMG_5776.png","keywords":["Business","Veranstaltungen"],"articleSection":["Alle News","Business","Veranstaltungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/","url":"https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/","name":"PROSE-Schweden bei Train&Rail \u2013 Recap - PROSE - Shaping tomorrow\u2019s mobility","isPartOf":{"@id":"https:\/\/prose.one\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/#primaryimage"},"image":{"@id":"https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/IMG_5776.png","datePublished":"2023-04-28T09:07:38+00:00","dateModified":"2023-09-06T07:38:29+00:00","breadcrumb":{"@id":"https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/#primaryimage","url":"https:\/\/prose.one\/wp-content\/uploads\/IMG_5776.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/IMG_5776.png","width":2250,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/prose.one\/de\/prose-schweden-bei-trainrail-recap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/prose.one\/de\/"},{"@type":"ListItem","position":2,"name":"PROSE-Schweden bei Train&#038;Rail \u2013 Recap"}]},{"@type":"WebSite","@id":"https:\/\/prose.one\/de\/#website","url":"https:\/\/prose.one\/de\/","name":"PROSE Shaping tomorrow\u2019s mobility","description":"Shaping tomorrow\u2019s mobility","publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prose.one\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/prose.one\/de\/#organization","name":"PROSE","url":"https:\/\/prose.one\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/","url":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","width":1182,"height":326,"caption":"PROSE"},"image":{"@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/prose-group"]},{"@type":"Person","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9","name":"Prose","url":"https:\/\/prose.one\/de\/author\/adminprose\/"}]}},"_links":{"self":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/8017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/comments?post=8017"}],"version-history":[{"count":1,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/8017\/revisions"}],"predecessor-version":[{"id":8018,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/8017\/revisions\/8018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media\/6990"}],"wp:attachment":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media?parent=8017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/categories?post=8017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/tags?post=8017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}