{"id":14384,"date":"2026-03-23T13:18:43","date_gmt":"2026-03-23T12:18:43","guid":{"rendered":"https:\/\/prose.one\/vehicle-life-extension-tilo-flirt\/"},"modified":"2026-03-23T13:25:44","modified_gmt":"2026-03-23T12:25:44","slug":"lebensdauerverlaengerung-tilo-flirt","status":"publish","type":"post","link":"https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/","title":{"rendered":"Lebensdauerverl\u00e4ngerung TILO FLIRT"},"content":{"rendered":"<h3 class=\"detail\">Kunde: SBB, Schweiz<\/h3>\n<h4>Projektaufgaben<\/h4>\n<ul>\n<li>Gesamtprojektleitung der Lebensdauerverl\u00e4ngerung TILO FLIRT<\/li>\n<li>Projekt Reporting an Lenkungsausschuss<\/li>\n<li>Projektplanung und Umsetzung der Detailkonzeptphase<\/li>\n<li>Finanzierungsantrag ARPV<\/li>\n<li>Projektplanung und Umsetzung der Realisierungsphase<\/li>\n<li>F\u00fchren des SBB-Projektteams<\/li>\n<\/ul>\n<h4>Unsere Umsetzung<\/h4>\n<p><span lang=\"DE-CH\">Die Schweizerischen Bundesbahnen (SBB) betreiben 54 Flirt-Z\u00fcge mit TILO. Diese Z\u00fcge wurden in f\u00fcnf Phasen zwischen 2007 und 2020 beschafft und sind f\u00fcr eine Lebensdauer von 25 Jahren ausgelegt. Um k\u00fcnftig alle TILO-Flirt-Z\u00fcge im Rahmen eines neuen Beschaffungsprojekts gleichzeitig ersetzen zu k\u00f6nnen, plant die SBB, die Lebensdauer der beiden \u00e4ltesten Teilflotten auf 32 Jahre zu verl\u00e4ngern.<\/span><\/p>\n<p>PROSE ist verantwortlich f\u00fcr die Gesamtleitung des Projekts zur Verl\u00e4ngerung der Lebensdauer der TILO-Zugflotte. W\u00e4hrend 2 \u00bd Jahren leiteten wir ein eigenes Projektteam innerhalb der SBB und sorgten f\u00fcr eine nahtlose Zusammenarbeit zwischen Kundenanforderungen, Technik, Entwicklung, Produktion, Qualit\u00e4t und Supply Chain Management.<\/p>\n<p>Ein wichtiger Meilenstein war die detaillierte Konzeptphase, in der PROSEs strukturierter Ansatz sicherstellte, dass das Anforderungsmanagement, die Entwicklung des technischen Konzepts und die Umsetzung des Prototyps p\u00fcnktlich und innerhalb des Budgets abgeschlossen wurden. Unser Fachwissen im Bereich der Zertifizierung spielte eine entscheidende Rolle bei der Erlangung der erforderlichen Genehmigungen f\u00fcr die Schweiz und Italien, ein wesentlicher Schritt, um das Projekt auf Kurs zu halten.<\/p>\n<p>PROSE war auch federf\u00fchrend bei der erfolgreichen Beantragung von F\u00f6rdermitteln (ARPV) bei den zust\u00e4ndigen Kantonen und dem Bundesamt f\u00fcr Verkehr (BAV), wodurch die Finanzierung des Umbaus der gesamten Flotte von 30 Z\u00fcgen sichergestellt wurde.<\/p>\n<p>W\u00e4hrend der Produktionsphase arbeiteten wir eng mit dem SBB-Produktionswerk zusammen, um einen reibungslosen \u00dcbergang zur Serienumr\u00fcstung zu gew\u00e4hrleisten. Nach erfolgreichem Produktionsstart \u00fcbergab PROSE das Projekt sorgf\u00e4ltig an die SBB und sicherte so den weiteren Fortschritt und die zuverl\u00e4ssige Zukunft der TILO-Flotte.<\/p>\n<h4>Kundennutzen<\/h4>\n<p>Mit PROSE als Partner profitiert der Kunde von einem umfassenden Know-how in den Bereichen Projektmanagement, Stakeholder Management, Projektplanung, Change Management und Kostenkontrolle. Unternehmerisches Denken, fundiertes technisches Wissen, aber auch Kenntnisse der SBB-Prozesse und -Organisationen sind f\u00fcr eine erfolgreiche Projektumsetzung unerl\u00e4sslich.<\/p>\n<p>Neben dem technischen Know-how war unser Verst\u00e4ndnis der SBB-Prozesse und -Organisation ein entscheidender Faktor, um das Projekt auf Kurs zu halten. Durch die Zusammenarbeit mit PROSE konnte der Kunde Ressourcenl\u00fccken \u00fcberbr\u00fccken, auf unser umfangreiches Netzwerk in der Bahnindustrie zur\u00fcckgreifen und von unabh\u00e4ngiger, fachkundiger Beratung profitieren, die zu einem erfolgreichen Projektergebnis f\u00fchrte.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/prose.one\/de\/unser-dienstleistungsangebot\/\"><img decoding=\"async\" class=\"alignnone wp-image-7606\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Strategie-Unterstutzung-Strategy-support.svg\" alt=\"\" width=\"150\" \/><\/a><a href=\"https:\/\/prose.one\/all-our-services\/\"> \u00a0<\/a><a href=\"https:\/\/prose.one\/de\/unser-dienstleistungsangebot\/\"><img decoding=\"async\" class=\"alignnone wp-image-7590\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Modernisierung-Modernisation.svg\" alt=\"\" width=\"150\" \/><\/a>\u00a0 <a href=\"https:\/\/prose.one\/de\/unser-dienstleistungsangebot\/\"><img decoding=\"async\" class=\"alignnone wp-image-7614\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Zulassungsmanagement-vehicle-authorisation.svg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kunde: SBB, Schweiz Projektaufgaben Gesamtprojektleitung der Lebensdauerverl\u00e4ngerung TILO FLIRT Projekt Reporting an Lenkungsausschuss Projektplanung und Umsetzung der Detailkonzeptphase Finanzierungsantrag ARPV Projektplanung und Umsetzung der Realisierungsphase F\u00fchren des SBB-Projektteams Unsere Umsetzung Die Schweizerischen Bundesbahnen (SBB) betreiben 54 Flirt-Z\u00fcge mit TILO. Diese Z\u00fcge wurden in f\u00fcnf Phasen zwischen 2007 und 2020 beschafft und sind f\u00fcr eine Lebensdauer [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":14382,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[137,132,136,135,130],"tags":[171,182,187],"class_list":["post-14384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-das-bahnsystem-beherrschen","category-ihr-schienenfahrzeug-bauen","category-ihr-team-starken","category-ihre-flotte-fit-machen","category-categories-referenzen","tag-modernisierung","tag-strategie-unterstutzung","tag-zulassungsmanagement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lebensdauerverl\u00e4ngerung TILO FLIRT - PROSE - Shaping tomorrow\u2019s mobility<\/title>\n<meta name=\"description\" content=\"Lebensdauerverl\u00e4ngerung - PROSE leitet das TILO FLIRT Upgrade und verl\u00e4ngert die Flottenlebensdauer auf 32 Jahre mit zertifizierten L\u00f6sungen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lebensdauerverl\u00e4ngerung TILO FLIRT - PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"og:description\" content=\"Lebensdauerverl\u00e4ngerung - PROSE leitet das TILO FLIRT Upgrade und verl\u00e4ngert die Flottenlebensdauer auf 32 Jahre mit zertifizierten L\u00f6sungen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/\" \/>\n<meta property=\"og:site_name\" content=\"PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-23T12:18:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T12:25:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prose.one\/wp-content\/uploads\/20260323-Vehicle-life-extension-TILO-FLIRT-web.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Livia In-Albon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Livia In-Albon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lebensdauerverlaengerung-tilo-flirt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lebensdauerverlaengerung-tilo-flirt\\\/\"},\"author\":{\"name\":\"Livia In-Albon\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/5dcf46831d13ad7f4ecbe64f70764ffe\"},\"headline\":\"Lebensdauerverl\u00e4ngerung TILO FLIRT\",\"datePublished\":\"2026-03-23T12:18:43+00:00\",\"dateModified\":\"2026-03-23T12:25:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lebensdauerverlaengerung-tilo-flirt\\\/\"},\"wordCount\":391,\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lebensdauerverlaengerung-tilo-flirt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20260323-Vehicle-life-extension-TILO-FLIRT-web.png\",\"keywords\":[\"Modernisierung\",\"Strategie-Unterst\u00fctzung\",\"Zulassungsmanagement\"],\"articleSection\":[\"Das Bahnsystem beherrschen\",\"Ihr Schienenfahrzeug bauen\",\"Ihr Team st\u00e4rken\",\"Ihre Flotte fit machen\",\"Kategorien Referenzen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lebensdauerverlaengerung-tilo-flirt\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/lebensdauerverlaengerung-tilo-flirt\\\/\",\"name\":\"Lebensdauerverl\u00e4ngerung TILO FLIRT - PROSE - Shaping tomorrow\u2019s mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lebensdauerverlaengerung-tilo-flirt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lebensdauerverlaengerung-tilo-flirt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20260323-Vehicle-life-extension-TILO-FLIRT-web.png\",\"datePublished\":\"2026-03-23T12:18:43+00:00\",\"dateModified\":\"2026-03-23T12:25:44+00:00\",\"description\":\"Lebensdauerverl\u00e4ngerung - PROSE leitet das TILO FLIRT Upgrade und verl\u00e4ngert die Flottenlebensdauer auf 32 Jahre mit zertifizierten L\u00f6sungen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lebensdauerverlaengerung-tilo-flirt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prose.one\\\/de\\\/lebensdauerverlaengerung-tilo-flirt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lebensdauerverlaengerung-tilo-flirt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20260323-Vehicle-life-extension-TILO-FLIRT-web.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20260323-Vehicle-life-extension-TILO-FLIRT-web.png\",\"width\":2000,\"height\":1500,\"caption\":\"TILO FLIRT Zug der SBB in der Schweiz im Projekt zur Lebensdauerverl\u00e4ngerung, moderner elektrischer Triebzug auf Gleisen.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/lebensdauerverlaengerung-tilo-flirt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/prose.one\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lebensdauerverl\u00e4ngerung TILO FLIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"name\":\"PROSE Shaping tomorrow\u2019s mobility\",\"description\":\"Shaping tomorrow\u2019s mobility\",\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prose.one\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\",\"name\":\"PROSE\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"width\":1182,\"height\":326,\"caption\":\"PROSE\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prose-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/5dcf46831d13ad7f4ecbe64f70764ffe\",\"name\":\"Livia In-Albon\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/author\\\/livia-in-albon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lebensdauerverl\u00e4ngerung TILO FLIRT - PROSE - Shaping tomorrow\u2019s mobility","description":"Lebensdauerverl\u00e4ngerung - PROSE leitet das TILO FLIRT Upgrade und verl\u00e4ngert die Flottenlebensdauer auf 32 Jahre mit zertifizierten L\u00f6sungen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/","og_locale":"de_DE","og_type":"article","og_title":"Lebensdauerverl\u00e4ngerung TILO FLIRT - PROSE - Shaping tomorrow\u2019s mobility","og_description":"Lebensdauerverl\u00e4ngerung - PROSE leitet das TILO FLIRT Upgrade und verl\u00e4ngert die Flottenlebensdauer auf 32 Jahre mit zertifizierten L\u00f6sungen.","og_url":"https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/","og_site_name":"PROSE - Shaping tomorrow\u2019s mobility","article_published_time":"2026-03-23T12:18:43+00:00","article_modified_time":"2026-03-23T12:25:44+00:00","og_image":[{"url":"https:\/\/prose.one\/wp-content\/uploads\/20260323-Vehicle-life-extension-TILO-FLIRT-web.png","width":2000,"height":1500,"type":"image\/png"}],"author":"Livia In-Albon","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Livia In-Albon","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/#article","isPartOf":{"@id":"https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/"},"author":{"name":"Livia In-Albon","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/5dcf46831d13ad7f4ecbe64f70764ffe"},"headline":"Lebensdauerverl\u00e4ngerung TILO FLIRT","datePublished":"2026-03-23T12:18:43+00:00","dateModified":"2026-03-23T12:25:44+00:00","mainEntityOfPage":{"@id":"https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/"},"wordCount":391,"publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"image":{"@id":"https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/20260323-Vehicle-life-extension-TILO-FLIRT-web.png","keywords":["Modernisierung","Strategie-Unterst\u00fctzung","Zulassungsmanagement"],"articleSection":["Das Bahnsystem beherrschen","Ihr Schienenfahrzeug bauen","Ihr Team st\u00e4rken","Ihre Flotte fit machen","Kategorien Referenzen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/","url":"https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/","name":"Lebensdauerverl\u00e4ngerung TILO FLIRT - PROSE - Shaping tomorrow\u2019s mobility","isPartOf":{"@id":"https:\/\/prose.one\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/#primaryimage"},"image":{"@id":"https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/20260323-Vehicle-life-extension-TILO-FLIRT-web.png","datePublished":"2026-03-23T12:18:43+00:00","dateModified":"2026-03-23T12:25:44+00:00","description":"Lebensdauerverl\u00e4ngerung - PROSE leitet das TILO FLIRT Upgrade und verl\u00e4ngert die Flottenlebensdauer auf 32 Jahre mit zertifizierten L\u00f6sungen.","breadcrumb":{"@id":"https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/#primaryimage","url":"https:\/\/prose.one\/wp-content\/uploads\/20260323-Vehicle-life-extension-TILO-FLIRT-web.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/20260323-Vehicle-life-extension-TILO-FLIRT-web.png","width":2000,"height":1500,"caption":"TILO FLIRT Zug der SBB in der Schweiz im Projekt zur Lebensdauerverl\u00e4ngerung, moderner elektrischer Triebzug auf Gleisen."},{"@type":"BreadcrumbList","@id":"https:\/\/prose.one\/de\/lebensdauerverlaengerung-tilo-flirt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/prose.one\/de\/"},{"@type":"ListItem","position":2,"name":"Lebensdauerverl\u00e4ngerung TILO FLIRT"}]},{"@type":"WebSite","@id":"https:\/\/prose.one\/de\/#website","url":"https:\/\/prose.one\/de\/","name":"PROSE Shaping tomorrow\u2019s mobility","description":"Shaping tomorrow\u2019s mobility","publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prose.one\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/prose.one\/de\/#organization","name":"PROSE","url":"https:\/\/prose.one\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/","url":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","width":1182,"height":326,"caption":"PROSE"},"image":{"@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/prose-group"]},{"@type":"Person","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/5dcf46831d13ad7f4ecbe64f70764ffe","name":"Livia In-Albon","url":"https:\/\/prose.one\/de\/author\/livia-in-albon\/"}]}},"_links":{"self":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/14384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/comments?post=14384"}],"version-history":[{"count":3,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/14384\/revisions"}],"predecessor-version":[{"id":14387,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/14384\/revisions\/14387"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media\/14382"}],"wp:attachment":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media?parent=14384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/categories?post=14384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/tags?post=14384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}