{"id":14070,"date":"2026-02-12T10:37:28","date_gmt":"2026-02-12T09:37:28","guid":{"rendered":"https:\/\/prose.one\/assessing-locomotive-compatibility\/"},"modified":"2026-02-13T10:37:15","modified_gmt":"2026-02-13T09:37:15","slug":"bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung","status":"publish","type":"post","link":"https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/","title":{"rendered":"Bewertung der Kompatibilit\u00e4t von Lokomotiven bei erh\u00f6hter Oberleitungsspannung"},"content":{"rendered":"<h3 class=\"detail\">Kunde: SJ AB, Schweden<br \/>\nEndkunde: Trafikverket, Schweden<\/h3>\n<h4>Projektaufgaben<\/h4>\n<ul>\n<li>Technische Untersuchung<\/li>\n<li>Recherche von Dokumentationen<\/li>\n<li>Identifizierung m\u00f6glicher \u00c4nderungen an Hochspannungskreisen von Lokomotiven<\/li>\n<li>Kostenvoranschlag f\u00fcr die \u00c4nderungen<\/li>\n<li>Integration der \u00c4nderungen in das tats\u00e4chliche System<\/li>\n<\/ul>\n<h4>Unsere Umsetzung<\/h4>\n<p>PROSE begann mit einer strukturierten \u00dcberpr\u00fcfung des Hochspannungssystems Rc6, wobei die Konstruktions-unterlagen, Komponentenspezifikationen und historischen \u00c4nderungsaufzeichnungen analysiert wurden, um die aktuelle technische Basis des Fahrzeugs zu ermitteln. Auf der Grundlage dieser Analyse bewerteten wir die Auswirkungen der erh\u00f6hten maximalen Spannung auf die Isolationskoordination, die Spannungsreserven der Komponenten und die Schutzsysteme. Wo erforderlich, entwickelten wir alternative technische L\u00f6sungen, um die Einhaltung der neuen Betriebsbedingungen sicherzustellen. Jede Option wurde sowohl aus technischer als auch aus wirtschaftlicher Sicht bewertet, einschliesslich Machbarkeit, Umsetzungsaufwand, betriebliche Auswirkungen und damit verbundene Risiken. Die Arbeiten wurden in engem Dialog mit SJ als Betreiber und Trafikverket als Infrastrukturbesitzer durchgef\u00fchrt, um Transparenz und Abstimmung w\u00e4hrend des gesamten Projekts zu gew\u00e4hrleisten.<\/p>\n<h4>Kundennutzen<\/h4>\n<p class=\"FSText\" style=\"margin-bottom: 0cm;\"><span lang=\"DE-CH\">Der Kunde erhielt eine transparente und technisch fundierte Entscheidungsgrundlage f\u00fcr den Betrieb der Rc6-Flotte unter erh\u00f6hter Oberleitungsspannung. Unsere unabh\u00e4ngige Bewertung kl\u00e4rte Spannungsreserven, Komponenten-beschr\u00e4nkungen und Schutzanforderungen und schuf so vollst\u00e4ndige Transparenz hinsichtlich technischer Risiken und \u00c4nderungsbedarf.<\/span><\/p>\n<p class=\"FSText\" style=\"margin-top: 0cm;\"><span lang=\"DE-CH\">Durch den systematischen Vergleich von Modernisierungsszenarien, einschliesslich der Auswirkungen auf Kosten und Umsetzung, erm\u00f6glichten wir SJ und Trafikverket, Massnahmen auf der Grundlage von Sicherheit, Betriebssicherheit und langfristigem Investitionsschutz zu priorisieren. Dank der fundierten Kenntnisse von PROSE \u00fcber schwedische Schienenfahrzeuge und Infrastruktur-Schnittstellen konnten die Betreiber eine technisch robuste und zukunftssichere L\u00f6sung sicherstellen, die den aktuellen Netzstandards entspricht.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/prose.one\/de\/unser-dienstleistungsangebot\/\"><img decoding=\"async\" class=\"alignnone wp-image-7590\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Modernisierung-Modernisation.svg\" alt=\"\" width=\"150\" \/> <\/a>\u00a0 <a href=\"https:\/\/prose.one\/de\/unser-dienstleistungsangebot\/\"><img decoding=\"async\" class=\"alignnone wp-image-7614\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Zulassungsmanagement-vehicle-authorisation.svg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0 \u00a0<a href=\"https:\/\/prose.one\/de\/unser-dienstleistungsangebot\/\"><img decoding=\"async\" class=\"alignnone wp-image-7584\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Elektrotechnik-Elektronik-Electrial-electronic-engineering.svg\" alt=\"\" width=\"150\" \/><\/a>\u00a0 \u00a0<a href=\"https:\/\/prose.one\/de\/unser-dienstleistungsangebot\/\"><img decoding=\"async\" class=\"alignnone wp-image-7612\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Validierung-Verifizierung-Validation-Verification.svg\" alt=\"\" width=\"150\" \/><\/a>\u00a0 \u00a0 <a href=\"https:\/\/prose.one\/de\/unser-dienstleistungsangebot\/\"><img decoding=\"async\" class=\"alignnone wp-image-4809\" src=\"https:\/\/prose.one\/wp-content\/uploads\/RAMS-LCC-1.svg\" alt=\"\" width=\"150\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kunde: SJ AB, Schweden Endkunde: Trafikverket, Schweden Projektaufgaben Technische Untersuchung Recherche von Dokumentationen Identifizierung m\u00f6glicher \u00c4nderungen an Hochspannungskreisen von Lokomotiven Kostenvoranschlag f\u00fcr die \u00c4nderungen Integration der \u00c4nderungen in das tats\u00e4chliche System Unsere Umsetzung PROSE begann mit einer strukturierten \u00dcberpr\u00fcfung des Hochspannungssystems Rc6, wobei die Konstruktions-unterlagen, Komponentenspezifikationen und historischen \u00c4nderungsaufzeichnungen analysiert wurden, um die aktuelle technische [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":14060,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[138,137,135,130],"tags":[163,171,186,187],"class_list":["post-14070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ausgewahlte-projekte","category-das-bahnsystem-beherrschen","category-ihre-flotte-fit-machen","category-categories-referenzen","tag-elektrotechnik","tag-modernisierung","tag-validierung-verifizierung","tag-zulassungsmanagement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bewertung der Kompatibilit\u00e4t von Lokomotiven bei erh\u00f6hter Oberleitungsspannung - PROSE - Shaping tomorrow\u2019s mobility<\/title>\n<meta name=\"description\" content=\"Bewertung der Lokomotivkompatibilit\u00e4t \u2013 PROSE liefert technische Analysen und Kostenbewertungen f\u00fcr den sicheren Hochspannungsbetrieb von Rc6.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bewertung der Kompatibilit\u00e4t von Lokomotiven bei erh\u00f6hter Oberleitungsspannung - PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"og:description\" content=\"Bewertung der Lokomotivkompatibilit\u00e4t \u2013 PROSE liefert technische Analysen und Kostenbewertungen f\u00fcr den sicheren Hochspannungsbetrieb von Rc6.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/\" \/>\n<meta property=\"og:site_name\" content=\"PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-12T09:37:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-13T09:37:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prose.one\/wp-content\/uploads\/20250212_Assessing-locomotive-compatibility-under-increased-overhead-line-voltage.png\" \/>\n\t<meta property=\"og:image:width\" content=\"837\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Prose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prose\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\\\/\"},\"author\":{\"name\":\"Prose\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\"},\"headline\":\"Bewertung der Kompatibilit\u00e4t von Lokomotiven bei erh\u00f6hter Oberleitungsspannung\",\"datePublished\":\"2026-02-12T09:37:28+00:00\",\"dateModified\":\"2026-02-13T09:37:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\\\/\"},\"wordCount\":264,\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20250212_Assessing-locomotive-compatibility-under-increased-overhead-line-voltage.png\",\"keywords\":[\"Elektrotechnik\",\"Modernisierung\",\"Validierung &amp; Verifizierung\",\"Zulassungsmanagement\"],\"articleSection\":[\"Ausgew\u00e4hlte Projekte\",\"Das Bahnsystem beherrschen\",\"Ihre Flotte fit machen\",\"Kategorien Referenzen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\\\/\",\"name\":\"Bewertung der Kompatibilit\u00e4t von Lokomotiven bei erh\u00f6hter Oberleitungsspannung - PROSE - Shaping tomorrow\u2019s mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20250212_Assessing-locomotive-compatibility-under-increased-overhead-line-voltage.png\",\"datePublished\":\"2026-02-12T09:37:28+00:00\",\"dateModified\":\"2026-02-13T09:37:15+00:00\",\"description\":\"Bewertung der Lokomotivkompatibilit\u00e4t \u2013 PROSE liefert technische Analysen und Kostenbewertungen f\u00fcr den sicheren Hochspannungsbetrieb von Rc6.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prose.one\\\/de\\\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20250212_Assessing-locomotive-compatibility-under-increased-overhead-line-voltage.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20250212_Assessing-locomotive-compatibility-under-increased-overhead-line-voltage.png\",\"width\":837,\"height\":628,\"caption\":\"Schwarze SJ Rc6-Elektrolokomotive an einem schwedischen Bahnhof, mit Stromabnehmer und Hochspannungsausr\u00fcstung auf dem Dach.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/prose.one\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bewertung der Kompatibilit\u00e4t von Lokomotiven bei erh\u00f6hter Oberleitungsspannung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"name\":\"PROSE Shaping tomorrow\u2019s mobility\",\"description\":\"Shaping tomorrow\u2019s mobility\",\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prose.one\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\",\"name\":\"PROSE\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"width\":1182,\"height\":326,\"caption\":\"PROSE\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prose-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\",\"name\":\"Prose\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/author\\\/adminprose\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bewertung der Kompatibilit\u00e4t von Lokomotiven bei erh\u00f6hter Oberleitungsspannung - PROSE - Shaping tomorrow\u2019s mobility","description":"Bewertung der Lokomotivkompatibilit\u00e4t \u2013 PROSE liefert technische Analysen und Kostenbewertungen f\u00fcr den sicheren Hochspannungsbetrieb von Rc6.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/","og_locale":"de_DE","og_type":"article","og_title":"Bewertung der Kompatibilit\u00e4t von Lokomotiven bei erh\u00f6hter Oberleitungsspannung - PROSE - Shaping tomorrow\u2019s mobility","og_description":"Bewertung der Lokomotivkompatibilit\u00e4t \u2013 PROSE liefert technische Analysen und Kostenbewertungen f\u00fcr den sicheren Hochspannungsbetrieb von Rc6.","og_url":"https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/","og_site_name":"PROSE - Shaping tomorrow\u2019s mobility","article_published_time":"2026-02-12T09:37:28+00:00","article_modified_time":"2026-02-13T09:37:15+00:00","og_image":[{"width":837,"height":628,"url":"https:\/\/prose.one\/wp-content\/uploads\/20250212_Assessing-locomotive-compatibility-under-increased-overhead-line-voltage.png","type":"image\/png"}],"author":"Prose","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Prose","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/#article","isPartOf":{"@id":"https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/"},"author":{"name":"Prose","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9"},"headline":"Bewertung der Kompatibilit\u00e4t von Lokomotiven bei erh\u00f6hter Oberleitungsspannung","datePublished":"2026-02-12T09:37:28+00:00","dateModified":"2026-02-13T09:37:15+00:00","mainEntityOfPage":{"@id":"https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/"},"wordCount":264,"publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"image":{"@id":"https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/20250212_Assessing-locomotive-compatibility-under-increased-overhead-line-voltage.png","keywords":["Elektrotechnik","Modernisierung","Validierung &amp; Verifizierung","Zulassungsmanagement"],"articleSection":["Ausgew\u00e4hlte Projekte","Das Bahnsystem beherrschen","Ihre Flotte fit machen","Kategorien Referenzen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/","url":"https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/","name":"Bewertung der Kompatibilit\u00e4t von Lokomotiven bei erh\u00f6hter Oberleitungsspannung - PROSE - Shaping tomorrow\u2019s mobility","isPartOf":{"@id":"https:\/\/prose.one\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/#primaryimage"},"image":{"@id":"https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/20250212_Assessing-locomotive-compatibility-under-increased-overhead-line-voltage.png","datePublished":"2026-02-12T09:37:28+00:00","dateModified":"2026-02-13T09:37:15+00:00","description":"Bewertung der Lokomotivkompatibilit\u00e4t \u2013 PROSE liefert technische Analysen und Kostenbewertungen f\u00fcr den sicheren Hochspannungsbetrieb von Rc6.","breadcrumb":{"@id":"https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/#primaryimage","url":"https:\/\/prose.one\/wp-content\/uploads\/20250212_Assessing-locomotive-compatibility-under-increased-overhead-line-voltage.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/20250212_Assessing-locomotive-compatibility-under-increased-overhead-line-voltage.png","width":837,"height":628,"caption":"Schwarze SJ Rc6-Elektrolokomotive an einem schwedischen Bahnhof, mit Stromabnehmer und Hochspannungsausr\u00fcstung auf dem Dach."},{"@type":"BreadcrumbList","@id":"https:\/\/prose.one\/de\/bewertung-der-kompatibilitaet-von-lokomotiven-bei-erhoehter-oberleitungsspannung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/prose.one\/de\/"},{"@type":"ListItem","position":2,"name":"Bewertung der Kompatibilit\u00e4t von Lokomotiven bei erh\u00f6hter Oberleitungsspannung"}]},{"@type":"WebSite","@id":"https:\/\/prose.one\/de\/#website","url":"https:\/\/prose.one\/de\/","name":"PROSE Shaping tomorrow\u2019s mobility","description":"Shaping tomorrow\u2019s mobility","publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prose.one\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/prose.one\/de\/#organization","name":"PROSE","url":"https:\/\/prose.one\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/","url":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","width":1182,"height":326,"caption":"PROSE"},"image":{"@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/prose-group"]},{"@type":"Person","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9","name":"Prose","url":"https:\/\/prose.one\/de\/author\/adminprose\/"}]}},"_links":{"self":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/14070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/comments?post=14070"}],"version-history":[{"count":3,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/14070\/revisions"}],"predecessor-version":[{"id":14074,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/14070\/revisions\/14074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media\/14060"}],"wp:attachment":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media?parent=14070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/categories?post=14070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/tags?post=14070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}