{"id":13950,"date":"2026-01-26T16:20:34","date_gmt":"2026-01-26T15:20:34","guid":{"rendered":"https:\/\/prose.one\/preparing-and-migrating-technical-documentation-into-the-prodoc-documentation-system\/"},"modified":"2026-01-27T13:34:03","modified_gmt":"2026-01-27T12:34:03","slug":"vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc","status":"publish","type":"post","link":"https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/","title":{"rendered":"Vorbereitung und Migration der technischen Dokumentation in das Dokumentationssystem PRO(doc)"},"content":{"rendered":"<h3 class=\"detail\">Kunde: Transdev, Deutschland<\/h3>\n<h4>Projektaufgaben<\/h4>\n<ul>\n<li>Projektmanagement<\/li>\n<li>Softwaremanagement<\/li>\n<li>Struktur des Dokumentenmanagementsystems<\/li>\n<li>Hochladen von Dokumenten in PRO(doc)<\/li>\n<li>Schulung<\/li>\n<\/ul>\n<h4>Unsere Umsetzung<\/h4>\n<p><span lang=\"DE-CH\">Die Transdev Hannover GmbH \u00fcbernahm 13 Bombardier ET425.5 Elektrotriebz\u00fcge, die zwischen 2008 und 2022 im Einsatz der S-Bahn Hannover waren. Mit der \u00dcbernahme der Flotte erhielt der Betreiber die vollst\u00e4ndige Herstellerdokumentation, einschliesslich Betriebsanleitungen, Wartungshandb\u00fcchern und Wartungsanweisungen. <\/span><\/p>\n<p><span lang=\"DE-CH\">PROSE wurde beauftragt, die vorhandene Dokumentation anzupassen und zu konsolidieren sowie Handb\u00fccher, Anweisungen und Richtlinien zu einer einheitlichen Dokumentationsbasis zusammenzuf\u00fchren. Ein wichtiger Teil des Projekts bestand darin, die Dokumentation f\u00fcr die Integration in das XML-basierte PRO(doc)-System vorzubereiten, um strukturierte Daten, standardisierte Inhalte und eine kontrollierte Versionsverwaltung zu gew\u00e4hrleisten. <\/span><\/p>\n<p><span lang=\"DE-CH\">Zu den Aufgaben geh\u00f6rte auch die Schulung der Transdev-Mitarbeitenden im Hochladen, Bearbeiten und Pflegen der Dokumentation in PRO(doc). Das Projekt basierte auf einer engen Zusammenarbeit zwischen PROSE Schweden und PROSE Deutschland, um das Know-how im Dokumentationsmanagement mit dem operativen Fahrzeugwissen zu kombinieren. <\/span><\/p>\n<p>PRO(doc) wurde als technische Dokumentationsumgebung verwendet, die speziell auf die Wartung von Z\u00fcgen zugeschnitten ist. Wir haben das Fachwissen von PROSE Schweden und PROSE Deutschland geb\u00fcndelt und dabei die Bereiche Projektmanagement, MadCap Flare, Dokumentenmanagement, Stylesheets, Regeln, XML-Strukturierung und Probleml\u00f6sung abgedeckt.<\/p>\n<p>Das gesamte verf\u00fcgbare Material wurde in die Bearbeitungsumgebung importiert. PDF-Dokumente wurden in Word konvertiert und hinsichtlich Stil, Metadaten und Layout harmonisiert. Die Dokumentstruktur und das Design wurden in MadCap Flare entwickelt, wo der Inhalt in einer konsistenten, produktbasierten Hierarchie und einem pflegbaren Inhaltsverzeichnis organisiert wurde.<\/p>\n<p>Azure DevOps wurde ausschliesslich f\u00fcr die Quellcodeverwaltung und Versionskontrolle eingesetzt, um paralleles Arbeiten zu erm\u00f6glichen. Eine Dokumentenliste, die entsprechend der produktbasierten Struktur der Norm in Excel erstellt und gepflegt wurde, diente w\u00e4hrend des gesamten Projekts als Arbeitsdokument und Checkliste. Kontinuierlicher technischer Support und transparente Kommunikation sorgten f\u00fcr eine effiziente Zusammenarbeit und die Nachvollziehbarkeit von Entscheidungen.<\/p>\n<h4>Kundennutzen<\/h4>\n<p>Transdev arbeitet nun mit einem standardisierten und gut strukturierten Dokumentationssatz, der eine effiziente Wartung und den t\u00e4glichen Betrieb unterst\u00fctzt. Die von PROSE entwickelte PRO(doc)-Dokumentationsssystem bietet eine durchsuchbare Datenbank mit kontrollierter Versionsverwaltung, die einen zuverl\u00e4ssigen Zugriff auf genehmigte Inhalte und Aktualisierungen gew\u00e4hrleistet.<\/p>\n<p>Die konsolidierten und migrierten Dokumente werden in einer einheitlichen Struktur ver\u00f6ffentlicht, die zuk\u00fcnftige \u00dcberarbeitungen vereinfacht. Das responsive Design von PRO(doc) erm\u00f6glicht die Nutzung auf jedem Ger\u00e4t, w\u00e4hrend die Erstellung und Aktualisierung von Dokumenten in MadCap Flare verwaltet und nach PRO(doc) exportiert wird. Dank der angebotenen Schulungen kann Transdev seine Dokumentation selbstst\u00e4ndig verwalten und wird bei Bedarf durch das unabh\u00e4ngige und spezialisierte Fachwissen von PROSE unterst\u00fctzt.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/prose.one\/de\/unser-dienstleistungsangebot\/\"><img decoding=\"async\" class=\"alignnone wp-image-7600\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Schulungen-Training.svg\" alt=\"\" width=\"150\" \/><\/a> \u00a0<a href=\"https:\/\/prose.one\/de\/unser-dienstleistungsangebot\/\"><img decoding=\"async\" class=\"alignnone wp-image-7608\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Technische-Dokumentation-Documentation-services.svg\" alt=\"\" width=\"150\" \/><\/a> <a href=\"https:\/\/prose.one\/all-our-services\/\">\u00a0<\/a><a href=\"https:\/\/prose.one\/de\/unser-dienstleistungsangebot\/\"><img decoding=\"async\" class=\"alignnone wp-image-4811\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Software-1.svg\" alt=\"\" width=\"150\" height=\"709\" \/><\/a>\u00a0 <a href=\"https:\/\/prose.one\/de\/unser-dienstleistungsangebot\/\"><img decoding=\"async\" class=\"alignnone wp-image-7594\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Projektmanagement-Project-Management.svg\" alt=\"\" width=\"150\" \/><\/a>\u00a0 <a href=\"https:\/\/prose.one\/de\/unser-dienstleistungsangebot\/\"><img decoding=\"async\" class=\"alignnone wp-image-7616\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Instandhaltungsunterstutzung-optimierung-Maintenance-support-and-optimisation-1.svg\" alt=\"\" width=\"150\" \/><\/a><a href=\"https:\/\/prose.one\/all-our-services\/\">\u00a0\u00a0<\/a><a href=\"https:\/\/prose.one\/de\/unser-dienstleistungsangebot\/\"><img decoding=\"async\" class=\"alignnone wp-image-7590\" src=\"https:\/\/prose.one\/wp-content\/uploads\/Modernisierung-Modernisation.svg\" alt=\"\" width=\"150\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kunde: Transdev, Deutschland Projektaufgaben Projektmanagement Softwaremanagement Struktur des Dokumentenmanagementsystems Hochladen von Dokumenten in PRO(doc) Schulung Unsere Umsetzung Die Transdev Hannover GmbH \u00fcbernahm 13 Bombardier ET425.5 Elektrotriebz\u00fcge, die zwischen 2008 und 2022 im Einsatz der S-Bahn Hannover waren. Mit der \u00dcbernahme der Flotte erhielt der Betreiber die vollst\u00e4ndige Herstellerdokumentation, einschliesslich Betriebsanleitungen, Wartungshandb\u00fcchern und Wartungsanweisungen. PROSE wurde [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":13962,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[135,130],"tags":[190,171,175,184,181,120],"class_list":["post-13950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ihre-flotte-fit-machen","category-categories-referenzen","tag-instandhaltungsunterstutzung-optimierung","tag-modernisierung","tag-projektmanagement","tag-schulungen","tag-software-de","tag-technische-dokumentation-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vorbereitung und Migration der technischen Dokumentation in das Dokumentationssystem PRO(doc) - PROSE - Shaping tomorrow\u2019s mobility<\/title>\n<meta name=\"description\" content=\"Technische Dokumentationsverwaltung: PROSE konsolidiert und strukturiert Wartungshandb\u00fccher in XML-basierten Systemen f\u00fcr eine effiziente, kontrollierte Instandhaltung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vorbereitung und Migration der technischen Dokumentation in das Dokumentationssystem PRO(doc) - PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"og:description\" content=\"Technische Dokumentationsverwaltung: PROSE konsolidiert und strukturiert Wartungshandb\u00fccher in XML-basierten Systemen f\u00fcr eine effiziente, kontrollierte Instandhaltung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/\" \/>\n<meta property=\"og:site_name\" content=\"PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-26T15:20:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T12:34:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prose.one\/wp-content\/uploads\/20260126-Preparing-and-migrating-technical-documentation-into-5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Livia In-Albon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Livia In-Albon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\\\/\"},\"author\":{\"name\":\"Livia In-Albon\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/5dcf46831d13ad7f4ecbe64f70764ffe\"},\"headline\":\"Vorbereitung und Migration der technischen Dokumentation in das Dokumentationssystem PRO(doc)\",\"datePublished\":\"2026-01-26T15:20:34+00:00\",\"dateModified\":\"2026-01-27T12:34:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\\\/\"},\"wordCount\":436,\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20260126-Preparing-and-migrating-technical-documentation-into-5.png\",\"keywords\":[\"Instandhaltungsunterst\u00fctzung &amp; -optimierung\",\"Modernisierung\",\"Projektmanagement\",\"Schulungen\",\"Software\",\"Technische Dokumentation\"],\"articleSection\":[\"Ihre Flotte fit machen\",\"Kategorien Referenzen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\\\/\",\"name\":\"Vorbereitung und Migration der technischen Dokumentation in das Dokumentationssystem PRO(doc) - PROSE - Shaping tomorrow\u2019s mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20260126-Preparing-and-migrating-technical-documentation-into-5.png\",\"datePublished\":\"2026-01-26T15:20:34+00:00\",\"dateModified\":\"2026-01-27T12:34:03+00:00\",\"description\":\"Technische Dokumentationsverwaltung: PROSE konsolidiert und strukturiert Wartungshandb\u00fccher in XML-basierten Systemen f\u00fcr eine effiziente, kontrollierte Instandhaltung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prose.one\\\/de\\\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20260126-Preparing-and-migrating-technical-documentation-into-5.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20260126-Preparing-and-migrating-technical-documentation-into-5.png\",\"width\":2000,\"height\":1500,\"caption\":\"Bild des Prozesses von PRO(doc).\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/prose.one\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vorbereitung und Migration der technischen Dokumentation in das Dokumentationssystem PRO(doc)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"name\":\"PROSE Shaping tomorrow\u2019s mobility\",\"description\":\"Shaping tomorrow\u2019s mobility\",\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prose.one\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\",\"name\":\"PROSE\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"width\":1182,\"height\":326,\"caption\":\"PROSE\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prose-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/5dcf46831d13ad7f4ecbe64f70764ffe\",\"name\":\"Livia In-Albon\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/author\\\/livia-in-albon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vorbereitung und Migration der technischen Dokumentation in das Dokumentationssystem PRO(doc) - PROSE - Shaping tomorrow\u2019s mobility","description":"Technische Dokumentationsverwaltung: PROSE konsolidiert und strukturiert Wartungshandb\u00fccher in XML-basierten Systemen f\u00fcr eine effiziente, kontrollierte Instandhaltung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/","og_locale":"de_DE","og_type":"article","og_title":"Vorbereitung und Migration der technischen Dokumentation in das Dokumentationssystem PRO(doc) - PROSE - Shaping tomorrow\u2019s mobility","og_description":"Technische Dokumentationsverwaltung: PROSE konsolidiert und strukturiert Wartungshandb\u00fccher in XML-basierten Systemen f\u00fcr eine effiziente, kontrollierte Instandhaltung.","og_url":"https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/","og_site_name":"PROSE - Shaping tomorrow\u2019s mobility","article_published_time":"2026-01-26T15:20:34+00:00","article_modified_time":"2026-01-27T12:34:03+00:00","og_image":[{"width":2000,"height":1500,"url":"https:\/\/prose.one\/wp-content\/uploads\/20260126-Preparing-and-migrating-technical-documentation-into-5.png","type":"image\/png"}],"author":"Livia In-Albon","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Livia In-Albon","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/#article","isPartOf":{"@id":"https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/"},"author":{"name":"Livia In-Albon","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/5dcf46831d13ad7f4ecbe64f70764ffe"},"headline":"Vorbereitung und Migration der technischen Dokumentation in das Dokumentationssystem PRO(doc)","datePublished":"2026-01-26T15:20:34+00:00","dateModified":"2026-01-27T12:34:03+00:00","mainEntityOfPage":{"@id":"https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/"},"wordCount":436,"publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"image":{"@id":"https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/20260126-Preparing-and-migrating-technical-documentation-into-5.png","keywords":["Instandhaltungsunterst\u00fctzung &amp; -optimierung","Modernisierung","Projektmanagement","Schulungen","Software","Technische Dokumentation"],"articleSection":["Ihre Flotte fit machen","Kategorien Referenzen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/","url":"https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/","name":"Vorbereitung und Migration der technischen Dokumentation in das Dokumentationssystem PRO(doc) - PROSE - Shaping tomorrow\u2019s mobility","isPartOf":{"@id":"https:\/\/prose.one\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/#primaryimage"},"image":{"@id":"https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/20260126-Preparing-and-migrating-technical-documentation-into-5.png","datePublished":"2026-01-26T15:20:34+00:00","dateModified":"2026-01-27T12:34:03+00:00","description":"Technische Dokumentationsverwaltung: PROSE konsolidiert und strukturiert Wartungshandb\u00fccher in XML-basierten Systemen f\u00fcr eine effiziente, kontrollierte Instandhaltung.","breadcrumb":{"@id":"https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/#primaryimage","url":"https:\/\/prose.one\/wp-content\/uploads\/20260126-Preparing-and-migrating-technical-documentation-into-5.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/20260126-Preparing-and-migrating-technical-documentation-into-5.png","width":2000,"height":1500,"caption":"Bild des Prozesses von PRO(doc)."},{"@type":"BreadcrumbList","@id":"https:\/\/prose.one\/de\/vorbereitung-und-migration-der-technischen-dokumentation-in-das-dokumentationssystem-prodoc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/prose.one\/de\/"},{"@type":"ListItem","position":2,"name":"Vorbereitung und Migration der technischen Dokumentation in das Dokumentationssystem PRO(doc)"}]},{"@type":"WebSite","@id":"https:\/\/prose.one\/de\/#website","url":"https:\/\/prose.one\/de\/","name":"PROSE Shaping tomorrow\u2019s mobility","description":"Shaping tomorrow\u2019s mobility","publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prose.one\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/prose.one\/de\/#organization","name":"PROSE","url":"https:\/\/prose.one\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/","url":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","width":1182,"height":326,"caption":"PROSE"},"image":{"@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/prose-group"]},{"@type":"Person","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/5dcf46831d13ad7f4ecbe64f70764ffe","name":"Livia In-Albon","url":"https:\/\/prose.one\/de\/author\/livia-in-albon\/"}]}},"_links":{"self":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/13950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/comments?post=13950"}],"version-history":[{"count":4,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/13950\/revisions"}],"predecessor-version":[{"id":13974,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/13950\/revisions\/13974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media\/13962"}],"wp:attachment":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media?parent=13950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/categories?post=13950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/tags?post=13950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}