{"id":13106,"date":"2025-08-12T10:52:24","date_gmt":"2025-08-12T09:52:24","guid":{"rendered":"https:\/\/prose.one\/prose-qualifies-in-43-of-56-service-areas-at-norske-tog-as\/"},"modified":"2025-08-12T11:01:36","modified_gmt":"2025-08-12T10:01:36","slug":"prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as","status":"publish","type":"post","link":"https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/","title":{"rendered":"PROSE qualifiziert sich in 43 von 56 Dienstleistungsbereichen bei Norske tog AS"},"content":{"rendered":"<p>Wir sind stolz, gemeinsam mit <a class=\"OIiVCOxbjYJdFWNnheMOpPSQfXcdLwVS \" tabindex=\"0\" href=\"https:\/\/www.linkedin.com\/company\/mantena\/\" target=\"_self\" data-test-app-aware-link=\"\">Mantena Nordic<\/a> und <a class=\"OIiVCOxbjYJdFWNnheMOpPSQfXcdLwVS \" tabindex=\"0\" href=\"https:\/\/www.linkedin.com\/company\/berge-consulting-as\/\" target=\"_self\" data-test-app-aware-link=\"\">Railsupport AS<\/a> im neuen Rahmenvertrag von <a class=\"OIiVCOxbjYJdFWNnheMOpPSQfXcdLwVS \" tabindex=\"0\" href=\"https:\/\/www.linkedin.com\/company\/norske-tog\/\" target=\"_self\" data-test-app-aware-link=\"\">Norske tog AS<\/a> vertreten zu sein und uns in 43 von 56 Dienstleistungsbereichen qualifiziert zu haben. Dieser Erfolg ist das Ergebnis einer engen Zusammenarbeit, bei der sich unsere bahntechnische Expertise, unsere fundierten betrieblichen Kenntnisse und unser agiler Ansatz zu einem \u00fcberzeugenden Angebot vereint haben.<\/p>\n<p>Wir werden <a class=\"OIiVCOxbjYJdFWNnheMOpPSQfXcdLwVS \" tabindex=\"0\" href=\"https:\/\/www.linkedin.com\/company\/norske-tog\/\" target=\"_self\" data-test-app-aware-link=\"\">Norske tog AS<\/a> dabei unterst\u00fctzen, eine Vielzahl von Bereichen der Eisenbahntechnik zu bewerten, zu analysieren, zu koordinieren und zu optimieren, um so zu sicheren, effizienten und zuverl\u00e4ssigen Z\u00fcgen f\u00fcr die Zukunft beizutragen.<\/p>\n<p>Vielen Dank f\u00fcr Ihr Vertrauen, <a class=\"OIiVCOxbjYJdFWNnheMOpPSQfXcdLwVS \" tabindex=\"0\" href=\"https:\/\/www.linkedin.com\/company\/norske-tog\/\" target=\"_self\" data-test-app-aware-link=\"\">Norske tog AS<\/a>.<\/p>\n<p>Mehr dazu (nur auf Norwegisch): <a href=\"https:\/\/kommunikasjon.ntb.no\/pressemelding\/18609556\/mantena-gjor-storeslem-i-rammeavtale-med-norske-tog-strategisk-samarbeid-ga-uttelling?publisherId=17848828&amp;lang=no\">Mantena gj\u00f8r storeslem i rammeavtale med Norske tog \u2013 strategisk samarbeid ga uttelling | Mantena<\/a><br \/>\nInteressiert, was wir f\u00fcr Sie tun k\u00f6nnen? Wenden Sie sich an Ihr lokales B\u00fcro oder an unsere internationale Abteilung: <a href=\"https:\/\/prose.one\/de\/kontakt\/\">Kontakt &#8211; PROSE &#8211; Shaping tomorrow\u2019s mobility<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir sind stolz, gemeinsam mit Mantena Nordic und Railsupport AS im neuen Rahmenvertrag von Norske tog AS vertreten zu sein und uns in 43 von 56 Dienstleistungsbereichen qualifiziert zu haben. Dieser Erfolg ist das Ergebnis einer engen Zusammenarbeit, bei der sich unsere bahntechnische Expertise, unsere fundierten betrieblichen Kenntnisse und unser agiler Ansatz zu einem \u00fcberzeugenden [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":13104,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117],"tags":[159],"class_list":["post-13106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-de","tag-business-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PROSE qualifiziert sich in 43 von 56 Dienstleistungsbereichen bei Norske tog AS - PROSE - Shaping tomorrow\u2019s mobility<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PROSE qualifiziert sich in 43 von 56 Dienstleistungsbereichen bei Norske tog AS - PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"og:description\" content=\"Wir sind stolz, gemeinsam mit Mantena Nordic und Railsupport AS im neuen Rahmenvertrag von Norske tog AS vertreten zu sein und uns in 43 von 56 Dienstleistungsbereichen qualifiziert zu haben. Dieser Erfolg ist das Ergebnis einer engen Zusammenarbeit, bei der sich unsere bahntechnische Expertise, unsere fundierten betrieblichen Kenntnisse und unser agiler Ansatz zu einem \u00fcberzeugenden [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/\" \/>\n<meta property=\"og:site_name\" content=\"PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-12T09:52:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-12T10:01:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prose.one\/wp-content\/uploads\/20250812-PROSE-qualifies-in-43-of-56-service-areas-at-Norske-tog-AS.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1612\" \/>\n\t<meta property=\"og:image:height\" content=\"1075\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Livia In-Albon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Livia In-Albon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\\\/\"},\"author\":{\"name\":\"Livia In-Albon\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/5dcf46831d13ad7f4ecbe64f70764ffe\"},\"headline\":\"PROSE qualifiziert sich in 43 von 56 Dienstleistungsbereichen bei Norske tog AS\",\"datePublished\":\"2025-08-12T09:52:24+00:00\",\"dateModified\":\"2025-08-12T10:01:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\\\/\"},\"wordCount\":162,\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20250812-PROSE-qualifies-in-43-of-56-service-areas-at-Norske-tog-AS.png\",\"keywords\":[\"Business\"],\"articleSection\":[\"Alle News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\\\/\",\"name\":\"PROSE qualifiziert sich in 43 von 56 Dienstleistungsbereichen bei Norske tog AS - PROSE - Shaping tomorrow\u2019s mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20250812-PROSE-qualifies-in-43-of-56-service-areas-at-Norske-tog-AS.png\",\"datePublished\":\"2025-08-12T09:52:24+00:00\",\"dateModified\":\"2025-08-12T10:01:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prose.one\\\/de\\\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20250812-PROSE-qualifies-in-43-of-56-service-areas-at-Norske-tog-AS.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20250812-PROSE-qualifies-in-43-of-56-service-areas-at-Norske-tog-AS.png\",\"width\":1612,\"height\":1075},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/prose.one\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROSE qualifiziert sich in 43 von 56 Dienstleistungsbereichen bei Norske tog AS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"name\":\"PROSE Shaping tomorrow\u2019s mobility\",\"description\":\"Shaping tomorrow\u2019s mobility\",\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prose.one\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\",\"name\":\"PROSE\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"width\":1182,\"height\":326,\"caption\":\"PROSE\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prose-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/5dcf46831d13ad7f4ecbe64f70764ffe\",\"name\":\"Livia In-Albon\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/author\\\/livia-in-albon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PROSE qualifiziert sich in 43 von 56 Dienstleistungsbereichen bei Norske tog AS - PROSE - Shaping tomorrow\u2019s mobility","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/","og_locale":"de_DE","og_type":"article","og_title":"PROSE qualifiziert sich in 43 von 56 Dienstleistungsbereichen bei Norske tog AS - PROSE - Shaping tomorrow\u2019s mobility","og_description":"Wir sind stolz, gemeinsam mit Mantena Nordic und Railsupport AS im neuen Rahmenvertrag von Norske tog AS vertreten zu sein und uns in 43 von 56 Dienstleistungsbereichen qualifiziert zu haben. Dieser Erfolg ist das Ergebnis einer engen Zusammenarbeit, bei der sich unsere bahntechnische Expertise, unsere fundierten betrieblichen Kenntnisse und unser agiler Ansatz zu einem \u00fcberzeugenden [&hellip;]","og_url":"https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/","og_site_name":"PROSE - Shaping tomorrow\u2019s mobility","article_published_time":"2025-08-12T09:52:24+00:00","article_modified_time":"2025-08-12T10:01:36+00:00","og_image":[{"width":1612,"height":1075,"url":"https:\/\/prose.one\/wp-content\/uploads\/20250812-PROSE-qualifies-in-43-of-56-service-areas-at-Norske-tog-AS.png","type":"image\/png"}],"author":"Livia In-Albon","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Livia In-Albon","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/#article","isPartOf":{"@id":"https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/"},"author":{"name":"Livia In-Albon","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/5dcf46831d13ad7f4ecbe64f70764ffe"},"headline":"PROSE qualifiziert sich in 43 von 56 Dienstleistungsbereichen bei Norske tog AS","datePublished":"2025-08-12T09:52:24+00:00","dateModified":"2025-08-12T10:01:36+00:00","mainEntityOfPage":{"@id":"https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/"},"wordCount":162,"publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"image":{"@id":"https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/20250812-PROSE-qualifies-in-43-of-56-service-areas-at-Norske-tog-AS.png","keywords":["Business"],"articleSection":["Alle News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/","url":"https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/","name":"PROSE qualifiziert sich in 43 von 56 Dienstleistungsbereichen bei Norske tog AS - PROSE - Shaping tomorrow\u2019s mobility","isPartOf":{"@id":"https:\/\/prose.one\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/#primaryimage"},"image":{"@id":"https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/20250812-PROSE-qualifies-in-43-of-56-service-areas-at-Norske-tog-AS.png","datePublished":"2025-08-12T09:52:24+00:00","dateModified":"2025-08-12T10:01:36+00:00","breadcrumb":{"@id":"https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/#primaryimage","url":"https:\/\/prose.one\/wp-content\/uploads\/20250812-PROSE-qualifies-in-43-of-56-service-areas-at-Norske-tog-AS.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/20250812-PROSE-qualifies-in-43-of-56-service-areas-at-Norske-tog-AS.png","width":1612,"height":1075},{"@type":"BreadcrumbList","@id":"https:\/\/prose.one\/de\/prose-qualifiziert-sich-in-43-von-56-dienstleistungsbereichen-bei-norske-tog-as\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/prose.one\/de\/"},{"@type":"ListItem","position":2,"name":"PROSE qualifiziert sich in 43 von 56 Dienstleistungsbereichen bei Norske tog AS"}]},{"@type":"WebSite","@id":"https:\/\/prose.one\/de\/#website","url":"https:\/\/prose.one\/de\/","name":"PROSE Shaping tomorrow\u2019s mobility","description":"Shaping tomorrow\u2019s mobility","publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prose.one\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/prose.one\/de\/#organization","name":"PROSE","url":"https:\/\/prose.one\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/","url":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","width":1182,"height":326,"caption":"PROSE"},"image":{"@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/prose-group"]},{"@type":"Person","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/5dcf46831d13ad7f4ecbe64f70764ffe","name":"Livia In-Albon","url":"https:\/\/prose.one\/de\/author\/livia-in-albon\/"}]}},"_links":{"self":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/13106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/comments?post=13106"}],"version-history":[{"count":2,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/13106\/revisions"}],"predecessor-version":[{"id":13108,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/13106\/revisions\/13108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media\/13104"}],"wp:attachment":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media?parent=13106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/categories?post=13106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/tags?post=13106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}