{"id":12554,"date":"2025-03-25T15:06:03","date_gmt":"2025-03-25T14:06:03","guid":{"rendered":"https:\/\/prose.one\/teaching-at-tu-berlin\/"},"modified":"2025-03-26T12:50:56","modified_gmt":"2025-03-26T11:50:56","slug":"vorlesung-an-tu-berlin","status":"publish","type":"post","link":"https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/","title":{"rendered":"Von der Theorie zu realen Bahnl\u00f6sungen: PROSE \u00fcbernimmt Vorlesung an der TU Berlin"},"content":{"rendered":"<p>PROSE-Experten werden ab dem Sommersemester 2025 an der <a href=\"https:\/\/www.linkedin.com\/school\/tuberlin\/\"><strong>Technische Universit\u00e4t Berlin<\/strong><\/a> die Vorlesung \u201eFahrdynamik von Schienenfahrzeugen &#8211; Theorie\u201c halten. Die Vorlesung vermittelt die theoretischen Grundlagen der Fahrdynamik von Schienenfahrzeugen und deren Berechnung mittels Computersimulation. Im Mittelpunkt stehen dabei der Rad-Schiene-Kontakt, das Schwingungsverhalten im Fahrbetrieb und die Besonderheiten der Kurvenfahrt.<\/p>\n<p><strong>Warum ist das wichtig?<\/strong><\/p>\n<p>Das Verst\u00e4ndnis der Dynamik von Schienenfahrzeugen ist der Schl\u00fcssel dazu, Z\u00fcge sicherer, stabiler und komfortabler zu machen. Indem wir die Theorie mit unseren Erfahrungen aus der Praxis verbinden, k\u00f6nnen wir den Student:innen praktische Einblicke in die Herausforderungen geben, denen sie als zuk\u00fcnftige Ingenieur:innen gegen\u00fcberstehen werden. Und diese Vorlesung\u00a0 ist keine Einbahnstrasse &#8211; wir werden auch viel von den Fragen und frischen Ideen lernen, die die Student:innen mitbringen.<\/p>\n<p>Wir freuen uns darauf, unser Wissen weiterzugeben und die n\u00e4chste Generation von Eisenbahningenieur:innen auszubilden!<\/p>\n<p>Unser Team &#8211; Prof. Dr.-Ing. <a href=\"https:\/\/www.linkedin.com\/in\/bernhard-kurzeck-6866207b\/\"><strong>Bernhard Kurzeck<\/strong><\/a> (bereits Honorarprofessor an der TU Berlin), Dr.-Ing. <a href=\"https:\/\/www.linkedin.com\/in\/johannes-keudel-036b28126\/\"><strong>Johannes Keudel<\/strong><\/a>, und Dr.-Ing. Andr\u00e9 Theiler &#8211; wird die Nachfolge von Prof. Dr.-Ing. <a href=\"https:\/\/www.linkedin.com\/in\/oldrich-polach-064954127\/\"><strong>Oldrich Polach<\/strong><\/a> antreten, der die Vorlesung viele Jahre lang gehalten hat und sie nun an die n\u00e4chste Generation von Experten weitergibt.<\/p>\n<p>Wir sind immer auf der Suche nach brillanten K\u00f6pfen, <a href=\"https:\/\/prose.one\/de\/bei-uns-arbeiten\/\">werfen Sie einen Blick auf unsere offenen Stellen.<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PROSE-Experten werden ab dem Sommersemester 2025 an der Technische Universit\u00e4t Berlin die Vorlesung \u201eFahrdynamik von Schienenfahrzeugen &#8211; Theorie\u201c halten. Die Vorlesung vermittelt die theoretischen Grundlagen der Fahrdynamik von Schienenfahrzeugen und deren Berechnung mittels Computersimulation. Im Mittelpunkt stehen dabei der Rad-Schiene-Kontakt, das Schwingungsverhalten im Fahrbetrieb und die Besonderheiten der Kurvenfahrt. Warum ist das wichtig? Das Verst\u00e4ndnis [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117,129],"tags":[159],"class_list":["post-12554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-de","category-business-de","tag-business-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Von der Theorie zu realen Bahnl\u00f6sungen: PROSE \u00fcbernimmt Vorlesung an der TU Berlin - PROSE - Shaping tomorrow\u2019s mobility<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Von der Theorie zu realen Bahnl\u00f6sungen: PROSE \u00fcbernimmt Vorlesung an der TU Berlin - PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"og:description\" content=\"PROSE-Experten werden ab dem Sommersemester 2025 an der Technische Universit\u00e4t Berlin die Vorlesung \u201eFahrdynamik von Schienenfahrzeugen &#8211; Theorie\u201c halten. Die Vorlesung vermittelt die theoretischen Grundlagen der Fahrdynamik von Schienenfahrzeugen und deren Berechnung mittels Computersimulation. Im Mittelpunkt stehen dabei der Rad-Schiene-Kontakt, das Schwingungsverhalten im Fahrbetrieb und die Besonderheiten der Kurvenfahrt. Warum ist das wichtig? Das Verst\u00e4ndnis [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/\" \/>\n<meta property=\"og:site_name\" content=\"PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-25T14:06:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-26T11:50:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prose.one\/wp-content\/uploads\/20250325_tu-berlin-teaching.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1382\" \/>\n\t<meta property=\"og:image:height\" content=\"921\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Prose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prose\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorlesung-an-tu-berlin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorlesung-an-tu-berlin\\\/\"},\"author\":{\"name\":\"Prose\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\"},\"headline\":\"Von der Theorie zu realen Bahnl\u00f6sungen: PROSE \u00fcbernimmt Vorlesung an der TU Berlin\",\"datePublished\":\"2025-03-25T14:06:03+00:00\",\"dateModified\":\"2025-03-26T11:50:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorlesung-an-tu-berlin\\\/\"},\"wordCount\":231,\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorlesung-an-tu-berlin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20250325_tu-berlin-teaching.png\",\"keywords\":[\"Business\"],\"articleSection\":[\"Alle News\",\"Business\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorlesung-an-tu-berlin\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/vorlesung-an-tu-berlin\\\/\",\"name\":\"Von der Theorie zu realen Bahnl\u00f6sungen: PROSE \u00fcbernimmt Vorlesung an der TU Berlin - PROSE - Shaping tomorrow\u2019s mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorlesung-an-tu-berlin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorlesung-an-tu-berlin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20250325_tu-berlin-teaching.png\",\"datePublished\":\"2025-03-25T14:06:03+00:00\",\"dateModified\":\"2025-03-26T11:50:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorlesung-an-tu-berlin\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prose.one\\\/de\\\/vorlesung-an-tu-berlin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorlesung-an-tu-berlin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20250325_tu-berlin-teaching.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/20250325_tu-berlin-teaching.png\",\"width\":1382,\"height\":921},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/vorlesung-an-tu-berlin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/prose.one\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Von der Theorie zu realen Bahnl\u00f6sungen: PROSE \u00fcbernimmt Vorlesung an der TU Berlin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"name\":\"PROSE Shaping tomorrow\u2019s mobility\",\"description\":\"Shaping tomorrow\u2019s mobility\",\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prose.one\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\",\"name\":\"PROSE\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"width\":1182,\"height\":326,\"caption\":\"PROSE\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prose-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\",\"name\":\"Prose\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/author\\\/adminprose\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Von der Theorie zu realen Bahnl\u00f6sungen: PROSE \u00fcbernimmt Vorlesung an der TU Berlin - PROSE - Shaping tomorrow\u2019s mobility","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/","og_locale":"de_DE","og_type":"article","og_title":"Von der Theorie zu realen Bahnl\u00f6sungen: PROSE \u00fcbernimmt Vorlesung an der TU Berlin - PROSE - Shaping tomorrow\u2019s mobility","og_description":"PROSE-Experten werden ab dem Sommersemester 2025 an der Technische Universit\u00e4t Berlin die Vorlesung \u201eFahrdynamik von Schienenfahrzeugen &#8211; Theorie\u201c halten. Die Vorlesung vermittelt die theoretischen Grundlagen der Fahrdynamik von Schienenfahrzeugen und deren Berechnung mittels Computersimulation. Im Mittelpunkt stehen dabei der Rad-Schiene-Kontakt, das Schwingungsverhalten im Fahrbetrieb und die Besonderheiten der Kurvenfahrt. Warum ist das wichtig? Das Verst\u00e4ndnis [&hellip;]","og_url":"https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/","og_site_name":"PROSE - Shaping tomorrow\u2019s mobility","article_published_time":"2025-03-25T14:06:03+00:00","article_modified_time":"2025-03-26T11:50:56+00:00","og_image":[{"width":1382,"height":921,"url":"https:\/\/prose.one\/wp-content\/uploads\/20250325_tu-berlin-teaching.png","type":"image\/png"}],"author":"Prose","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Prose","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/#article","isPartOf":{"@id":"https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/"},"author":{"name":"Prose","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9"},"headline":"Von der Theorie zu realen Bahnl\u00f6sungen: PROSE \u00fcbernimmt Vorlesung an der TU Berlin","datePublished":"2025-03-25T14:06:03+00:00","dateModified":"2025-03-26T11:50:56+00:00","mainEntityOfPage":{"@id":"https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/"},"wordCount":231,"publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"image":{"@id":"https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/20250325_tu-berlin-teaching.png","keywords":["Business"],"articleSection":["Alle News","Business"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/","url":"https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/","name":"Von der Theorie zu realen Bahnl\u00f6sungen: PROSE \u00fcbernimmt Vorlesung an der TU Berlin - PROSE - Shaping tomorrow\u2019s mobility","isPartOf":{"@id":"https:\/\/prose.one\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/#primaryimage"},"image":{"@id":"https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/20250325_tu-berlin-teaching.png","datePublished":"2025-03-25T14:06:03+00:00","dateModified":"2025-03-26T11:50:56+00:00","breadcrumb":{"@id":"https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/#primaryimage","url":"https:\/\/prose.one\/wp-content\/uploads\/20250325_tu-berlin-teaching.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/20250325_tu-berlin-teaching.png","width":1382,"height":921},{"@type":"BreadcrumbList","@id":"https:\/\/prose.one\/de\/vorlesung-an-tu-berlin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/prose.one\/de\/"},{"@type":"ListItem","position":2,"name":"Von der Theorie zu realen Bahnl\u00f6sungen: PROSE \u00fcbernimmt Vorlesung an der TU Berlin"}]},{"@type":"WebSite","@id":"https:\/\/prose.one\/de\/#website","url":"https:\/\/prose.one\/de\/","name":"PROSE Shaping tomorrow\u2019s mobility","description":"Shaping tomorrow\u2019s mobility","publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prose.one\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/prose.one\/de\/#organization","name":"PROSE","url":"https:\/\/prose.one\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/","url":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","width":1182,"height":326,"caption":"PROSE"},"image":{"@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/prose-group"]},{"@type":"Person","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9","name":"Prose","url":"https:\/\/prose.one\/de\/author\/adminprose\/"}]}},"_links":{"self":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/12554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/comments?post=12554"}],"version-history":[{"count":2,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/12554\/revisions"}],"predecessor-version":[{"id":12556,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/12554\/revisions\/12556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media\/12552"}],"wp:attachment":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media?parent=12554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/categories?post=12554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/tags?post=12554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}