{"id":10667,"date":"2025-01-27T09:58:03","date_gmt":"2025-01-27T08:58:03","guid":{"rendered":"https:\/\/prose.one\/projektleiter-schienenfahrzeuge-m-w-d\/"},"modified":"2025-02-12T12:51:26","modified_gmt":"2025-02-12T11:51:26","slug":"senior-projektleiter-schienenfahrzeuge-m-w-d","status":"publish","type":"post","link":"https:\/\/prose.one\/de\/senior-projektleiter-schienenfahrzeuge-m-w-d\/","title":{"rendered":"Senior Projektleiter Schienenfahrzeuge (m\/w\/d)"},"content":{"rendered":"<div class=\"col-md-8 col-lg-9 col-xl-8 text-lightgrey\">\n<div class=\"col-md-8 col-lg-9 col-xl-8 text-lightgrey\">\n<div class=\"col-md-8 col-lg-9 col-xl-8 text-lightgrey\">\n<div class=\"col-md-8 col-lg-9 col-xl-8 text-lightgrey\">\n<div class=\"col-md-8 col-lg-9 col-xl-8 text-lightgrey\">\n<div class=\"col-md-8 col-lg-9 col-xl-8 text-lightgrey\">\n<div class=\"col-md-8 col-lg-9 col-xl-8 text-lightgrey\">\n<div class=\"col-md-8 col-lg-9 col-xl-8 text-lightgrey\">\n<div class=\"col-md-8 col-lg-9 col-xl-8 text-lightgrey\">\n<div class=\"col-md-8 col-lg-9 col-xl-8 text-lightgrey\">\n<div class=\"col-md-8 col-lg-9 col-xl-8 text-lightgrey\">\n<div class=\"row wow fadeInLeft animated animated\" data-wow-delay=\"1.3s\">\n<div class=\"col-12\">\n<p>PROSE ist eines der f\u00fchrenden Unternehmen in Europa im Bereich des Mobility Engineering. Wir sind ein internationales Team, das Projekte \u201cvon A bis Z\u201d in den Bereichen Strategie, Einkauf, Zulassung, Entwicklung, Instandhaltung und Modernisierung erfolgreich umsetzt.<\/p>\n<p>Unser Ziel ist es, die Mobilit\u00e4t von Morgen zu gestalten. Hierf\u00fcr suchen wir eine(n) <strong>Senior Projektleiter Schienenfahrzeuge (60-100%)<\/strong>, um uns am Standort <strong>Schwaz, \u00d6sterreich<\/strong> beim Erreichen dieses Ziels zu unterst\u00fctzen. Kreativ, motiviert und einfallsreich \u2013 wir suchen eine selbstorganisierte und kommunikative Pers\u00f6nlichkeit, die unser Team erg\u00e4nzt.<\/p>\n<p>Als Senior Projektleiter verantworten Sie <strong>mittlere und grosse Projekte und Mandate<\/strong> im Mobilit\u00e4tsbereich prim\u00e4r gegen\u00fcber unseren Kunden im In- und Ausland. Das beinhaltet die Unterst\u00fctzung des Verkaufs w\u00e4hrend der Akquisitionsphase, die Gew\u00e4hrleistung des erfolgreichen Projektmanagements und der Qualit\u00e4tssicherung entlang des Lebenszyklus der Fahrzeuge (Entwicklung, Betrieb &amp; Instandhaltung, Modernisierung).<\/p>\n<h6><strong>Wir erwarten von Ihnen:<\/strong><\/h6>\n<ul>\n<li>Da unsere Passion <em>Shaping tomorrow\u2019s mobility<\/em> ist, vertrauen wir darauf, dass dies auch Ihre Leidenschaft ist. Um den Kundenbedarf nach innovativen L\u00f6sungen zu erf\u00fcllen, m\u00fcssen auch Sie einfallsreich sein.<\/li>\n<li>Als Senior Projektleiter in unserem Team sind Sie professionell, kommunikativ und selbstorganisiert. Unsere Mitarbeitenden sind selbstgetriebene, hochmotivierte und grossartige Teamkollegen.<\/li>\n<li>Sie verf\u00fcgen \u00fcber ausgewiesene Erfahrungen in der Bahnbranche und m\u00f6chten diese gern thematisch erweitern.<\/li>\n<li>Technischer Hochschulabschluss mit mehrj\u00e4hriger praktischer Erfahrung in der Entwicklung, im Projektmanagement oder im Betrieb von Schienenfahrzeugen, betriebswirtschaftliche Weiterbildung von Vorteil.<\/li>\n<li>Exzellente Kenntnisse in Deutsch (Muttersprache) und fliessend in Englisch.<\/li>\n<\/ul>\n<h6><strong>Was Sie von uns erwarten k\u00f6nnen:<\/strong><\/h6>\n<ul>\n<li>Ausgepr\u00e4gte Entrepreneur Kultur: In der Branche einmalige Gestaltungsfreiheit und Entscheidungskompetenz, flache Hierarchien.<\/li>\n<li>Flexibler Arbeitsort \/ Work anywhere: wir offerieren moderne Arbeitspl\u00e4tze in Schwaz, in Kombination mit Homeoffice und Arbeit beim Kunden vor Ort.<\/li>\n<li>Kontinuierliche Weiterentwicklung und job-spezifische Ausbildung.<\/li>\n<li>Vielseitigkeit, kein Projekt gleicht dem anderen.<\/li>\n<li>Ein engagiertes und internationales Team von Bahnexperten.<\/li>\n<li>\u00dcberkollektivvertragliche Bezahlung, ja nach Qualifikation und Erfahrung.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>PROSE bearbeitet und speichert Ihre Bewerbung w\u00e4hrend des Rekrutierungsprozesses gem\u00e4ss den Bestimmungen unserer Nutzungsbedingungen f\u00fcr Bewerber. Die Richtlinie ist unter <a href=\"https:\/\/prose.one\/de\/datenschutz\/\">https:\/\/prose.one\/de\/datenschutz\/<\/a> abrufbar. Indem Sie uns Ihre Bewerbungsunterlagen schicken, stimmen Sie der dort beschriebenen Verarbeitung und Speicherung Ihrer Daten zu.<\/p>\n<\/div>\n<\/div>\n<hr class=\"wow fadeIn animated animated\" data-wow-delay=\"0.3s\" \/>\n<div class=\"row wow fadeIn animated animated\" data-wow-delay=\"0.4s\">\n<div class=\"col-12\">\n<h4><strong>\u00dcber PROSE<\/strong><\/h4>\n<p>Bei PROSE kombinieren wir Fachwissen, Innovation und Unabh\u00e4ngigkeit, um erstklassige L\u00f6sungen im Bereich der Bahntechnik zu liefern. Als vertrauensw\u00fcrdiger Partner im Bereich Schienenfahrzeugtechnik und Eisenbahnberatung unterst\u00fctzen wir Hersteller, Betreiber und Beh\u00f6rden bei der Bew\u00e4ltigung ihrer Herausforderungen \u2013 \u00fcberall auf der Welt.<\/p>\n<p>Mit einem Team von \u00fcber 150 engagierten Fachleuten und einer Pr\u00e4senz in der Schweiz, Deutschland, Schweden, Italien, Frankreich und \u00d6sterreich sind wir bestrebt, die Mobilit\u00e4t von morgen zu gestalten.<\/p>\n<p>Seit unserer Gr\u00fcndung im Jahr 1982 haben wir uns mit \u00fcber 5\u2019000 erfolgreichen Projekten einen Namen als zuverl\u00e4ssiger Partner f\u00fcr die Bereitstellung innovativer Mobilit\u00e4tsl\u00f6sungen weltweit gemacht.<\/p>\n<\/div>\n<\/div>\n<div><a class=\"uk-button uk-button-primary uk-panel uk-margin-auto uk-panel uk-width-xlarge joinusbutton\" href=\"mailto:josef.kometer@prose.one?subject=Senior Projektleiter Schienenfahrzeuge (m\/w\/d)\" type=\"button\">Bewerben<\/a><a class=\"uk-button-text joinusbutton\" href=\"mailto:josef.kometer@prose.one?subject=Senior Projektleiter Schienenfahrzeuge (m\/w\/d)\" type=\"button\">Kontakt f\u00fcr Fragen<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>PROSE ist eines der f\u00fchrenden Unternehmen in Europa im Bereich des Mobility Engineering. Wir sind ein internationales Team, das Projekte \u201cvon A bis Z\u201d in den Bereichen Strategie, Einkauf, Zulassung, Entwicklung, Instandhaltung und Modernisierung erfolgreich umsetzt. Unser Ziel ist es, die Mobilit\u00e4t von Morgen zu gestalten. Hierf\u00fcr suchen wir eine(n) Senior Projektleiter Schienenfahrzeuge (60-100%), um [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[118,146],"tags":[174],"class_list":["post-10667","post","type-post","status-publish","format-standard","hentry","category-fur-prose-arbeiten-laender","category-osterreich","tag-projektmanagement-consulting"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senior Projektleiter Schienenfahrzeuge (m\/w\/d) - PROSE - Shaping tomorrow\u2019s mobility<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prose.one\/de\/senior-projektleiter-schienenfahrzeuge-m-w-d\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senior Projektleiter Schienenfahrzeuge (m\/w\/d) - PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"og:description\" content=\"PROSE ist eines der f\u00fchrenden Unternehmen in Europa im Bereich des Mobility Engineering. Wir sind ein internationales Team, das Projekte \u201cvon A bis Z\u201d in den Bereichen Strategie, Einkauf, Zulassung, Entwicklung, Instandhaltung und Modernisierung erfolgreich umsetzt. Unser Ziel ist es, die Mobilit\u00e4t von Morgen zu gestalten. Hierf\u00fcr suchen wir eine(n) Senior Projektleiter Schienenfahrzeuge (60-100%), um [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prose.one\/de\/senior-projektleiter-schienenfahrzeuge-m-w-d\/\" \/>\n<meta property=\"og:site_name\" content=\"PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-27T08:58:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-12T11:51:26+00:00\" \/>\n<meta name=\"author\" content=\"Prose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prose\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/senior-projektleiter-schienenfahrzeuge-m-w-d\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/senior-projektleiter-schienenfahrzeuge-m-w-d\\\/\"},\"author\":{\"name\":\"Prose\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\"},\"headline\":\"Senior Projektleiter Schienenfahrzeuge (m\\\/w\\\/d)\",\"datePublished\":\"2025-01-27T08:58:03+00:00\",\"dateModified\":\"2025-02-12T11:51:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/senior-projektleiter-schienenfahrzeuge-m-w-d\\\/\"},\"wordCount\":477,\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"keywords\":[\"Projektmanagement &amp; Consulting\"],\"articleSection\":[\"F\u00fcr PROSE arbeiten - L\u00e4nder\",\"\u00d6sterreich\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/senior-projektleiter-schienenfahrzeuge-m-w-d\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/senior-projektleiter-schienenfahrzeuge-m-w-d\\\/\",\"name\":\"Senior Projektleiter Schienenfahrzeuge (m\\\/w\\\/d) - PROSE - Shaping tomorrow\u2019s mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\"},\"datePublished\":\"2025-01-27T08:58:03+00:00\",\"dateModified\":\"2025-02-12T11:51:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/senior-projektleiter-schienenfahrzeuge-m-w-d\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prose.one\\\/de\\\/senior-projektleiter-schienenfahrzeuge-m-w-d\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/senior-projektleiter-schienenfahrzeuge-m-w-d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/prose.one\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Senior Projektleiter Schienenfahrzeuge (m\\\/w\\\/d)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"name\":\"PROSE Shaping tomorrow\u2019s mobility\",\"description\":\"Shaping tomorrow\u2019s mobility\",\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prose.one\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\",\"name\":\"PROSE\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"width\":1182,\"height\":326,\"caption\":\"PROSE\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prose-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/0765892f4bd10ddbc7f0f5cb92b799a9\",\"name\":\"Prose\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/author\\\/adminprose\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senior Projektleiter Schienenfahrzeuge (m\/w\/d) - PROSE - Shaping tomorrow\u2019s mobility","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prose.one\/de\/senior-projektleiter-schienenfahrzeuge-m-w-d\/","og_locale":"de_DE","og_type":"article","og_title":"Senior Projektleiter Schienenfahrzeuge (m\/w\/d) - PROSE - Shaping tomorrow\u2019s mobility","og_description":"PROSE ist eines der f\u00fchrenden Unternehmen in Europa im Bereich des Mobility Engineering. Wir sind ein internationales Team, das Projekte \u201cvon A bis Z\u201d in den Bereichen Strategie, Einkauf, Zulassung, Entwicklung, Instandhaltung und Modernisierung erfolgreich umsetzt. Unser Ziel ist es, die Mobilit\u00e4t von Morgen zu gestalten. Hierf\u00fcr suchen wir eine(n) Senior Projektleiter Schienenfahrzeuge (60-100%), um [&hellip;]","og_url":"https:\/\/prose.one\/de\/senior-projektleiter-schienenfahrzeuge-m-w-d\/","og_site_name":"PROSE - Shaping tomorrow\u2019s mobility","article_published_time":"2025-01-27T08:58:03+00:00","article_modified_time":"2025-02-12T11:51:26+00:00","author":"Prose","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Prose","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prose.one\/de\/senior-projektleiter-schienenfahrzeuge-m-w-d\/#article","isPartOf":{"@id":"https:\/\/prose.one\/de\/senior-projektleiter-schienenfahrzeuge-m-w-d\/"},"author":{"name":"Prose","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9"},"headline":"Senior Projektleiter Schienenfahrzeuge (m\/w\/d)","datePublished":"2025-01-27T08:58:03+00:00","dateModified":"2025-02-12T11:51:26+00:00","mainEntityOfPage":{"@id":"https:\/\/prose.one\/de\/senior-projektleiter-schienenfahrzeuge-m-w-d\/"},"wordCount":477,"publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"keywords":["Projektmanagement &amp; Consulting"],"articleSection":["F\u00fcr PROSE arbeiten - L\u00e4nder","\u00d6sterreich"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/prose.one\/de\/senior-projektleiter-schienenfahrzeuge-m-w-d\/","url":"https:\/\/prose.one\/de\/senior-projektleiter-schienenfahrzeuge-m-w-d\/","name":"Senior Projektleiter Schienenfahrzeuge (m\/w\/d) - PROSE - Shaping tomorrow\u2019s mobility","isPartOf":{"@id":"https:\/\/prose.one\/de\/#website"},"datePublished":"2025-01-27T08:58:03+00:00","dateModified":"2025-02-12T11:51:26+00:00","breadcrumb":{"@id":"https:\/\/prose.one\/de\/senior-projektleiter-schienenfahrzeuge-m-w-d\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prose.one\/de\/senior-projektleiter-schienenfahrzeuge-m-w-d\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prose.one\/de\/senior-projektleiter-schienenfahrzeuge-m-w-d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/prose.one\/de\/"},{"@type":"ListItem","position":2,"name":"Senior Projektleiter Schienenfahrzeuge (m\/w\/d)"}]},{"@type":"WebSite","@id":"https:\/\/prose.one\/de\/#website","url":"https:\/\/prose.one\/de\/","name":"PROSE Shaping tomorrow\u2019s mobility","description":"Shaping tomorrow\u2019s mobility","publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prose.one\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/prose.one\/de\/#organization","name":"PROSE","url":"https:\/\/prose.one\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/","url":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","width":1182,"height":326,"caption":"PROSE"},"image":{"@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/prose-group"]},{"@type":"Person","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/0765892f4bd10ddbc7f0f5cb92b799a9","name":"Prose","url":"https:\/\/prose.one\/de\/author\/adminprose\/"}]}},"_links":{"self":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/10667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/comments?post=10667"}],"version-history":[{"count":3,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/10667\/revisions"}],"predecessor-version":[{"id":12049,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/10667\/revisions\/12049"}],"wp:attachment":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media?parent=10667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/categories?post=10667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/tags?post=10667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}