{"id":10565,"date":"2024-04-25T12:10:43","date_gmt":"2024-04-25T11:10:43","guid":{"rendered":"https:\/\/prose.one\/safety-and-reliability-on-rails\/"},"modified":"2024-04-25T12:39:05","modified_gmt":"2024-04-25T11:39:05","slug":"sicherheit-und-zuverlaessigkeit-auf-schienen","status":"publish","type":"post","link":"https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/","title":{"rendered":"Sicherheit und Zuverl\u00e4ssigkeit auf Schienen &#8211; Ein Einblick in unser neustes Projekt"},"content":{"rendered":"<p>Bei PROSE sind wir stets bestrebt, die Sicherheit und Langlebigkeit der Fahrzeugflotten unserer Kund:innen zu maximieren. Bei unserem j\u00fcngsten Projekt haben wir umfassende Inspektionen an den X60A-Fahrzeugen durchgef\u00fchrt, um deren strukturelle Integrit\u00e4t sicherzustellen.<\/p>\n<p>Mit Hilfe von zerst\u00f6rungsfreien Pr\u00fcfungen, einschliesslich Magnetpulver- und Ultraschallpr\u00fcfungen, konnten wir Oberfl\u00e4chenfehler sowie innere Risse und Materialinhomogenit\u00e4ten identifizieren und dokumentieren. Diese gr\u00fcndlichen Untersuchungen erm\u00f6glichten es uns, m\u00f6gliche Schwachstellen genau zu identifizieren und gezielte Instandhaltungsmassnahmen zu planen, um die Sicherheit und Zuverl\u00e4ssigkeit der Fahrzeuge zu gew\u00e4hrleisten.<\/p>\n<p>Dank der detaillierten Dokumentation in neun Inspektionsberichten hat unser Kunde nun einen klaren \u00dcberblick \u00fcber den Zustand jedes einzelnen Fahrzeugs in seiner Flotte, was es ihm erleichtert, fundierte Entscheidungen \u00fcber Wartungs- und Reparaturmassnahmen zu treffen.<\/p>\n<p>Wir sind stolz darauf, die Betriebssicherheit zu erh\u00f6hen und unsere Kunden bei der strategischen Planung f\u00fcr die langfristige Instandhaltung ihrer Fahrzeugflotten zu unterst\u00fctzen.\u00a0Werfen Sie einen Blick auf die <a href=\"https:\/\/prose.one\/de\/inspektion-und-bewertung-von-karosserie-rissen-und-korrosion\/\">Referenz<\/a> zu diesem Projekt.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bei PROSE sind wir stets bestrebt, die Sicherheit und Langlebigkeit der Fahrzeugflotten unserer Kund:innen zu maximieren. Bei unserem j\u00fcngsten Projekt haben wir umfassende Inspektionen an den X60A-Fahrzeugen durchgef\u00fchrt, um deren strukturelle Integrit\u00e4t sicherzustellen. Mit Hilfe von zerst\u00f6rungsfreien Pr\u00fcfungen, einschliesslich Magnetpulver- und Ultraschallpr\u00fcfungen, konnten wir Oberfl\u00e4chenfehler sowie innere Risse und Materialinhomogenit\u00e4ten identifizieren und dokumentieren. Diese gr\u00fcndlichen [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":10563,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117,129],"tags":[159],"class_list":["post-10565","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-de","category-business-de","tag-business-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sicherheit und Zuverl\u00e4ssigkeit auf Schienen - Ein Einblick in unser neustes Projekt - PROSE - Shaping tomorrow\u2019s mobility<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sicherheit und Zuverl\u00e4ssigkeit auf Schienen - Ein Einblick in unser neustes Projekt - PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"og:description\" content=\"Bei PROSE sind wir stets bestrebt, die Sicherheit und Langlebigkeit der Fahrzeugflotten unserer Kund:innen zu maximieren. Bei unserem j\u00fcngsten Projekt haben wir umfassende Inspektionen an den X60A-Fahrzeugen durchgef\u00fchrt, um deren strukturelle Integrit\u00e4t sicherzustellen. Mit Hilfe von zerst\u00f6rungsfreien Pr\u00fcfungen, einschliesslich Magnetpulver- und Ultraschallpr\u00fcfungen, konnten wir Oberfl\u00e4chenfehler sowie innere Risse und Materialinhomogenit\u00e4ten identifizieren und dokumentieren. Diese gr\u00fcndlichen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/\" \/>\n<meta property=\"og:site_name\" content=\"PROSE - Shaping tomorrow\u2019s mobility\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-25T11:10:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-25T11:39:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prose.one\/wp-content\/uploads\/newsInspection-and-assessment-of-carbody-cracks-and-corrosion.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2250\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Livia In-Albon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Livia In-Albon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/sicherheit-und-zuverlaessigkeit-auf-schienen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/sicherheit-und-zuverlaessigkeit-auf-schienen\\\/\"},\"author\":{\"name\":\"Livia In-Albon\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/5dcf46831d13ad7f4ecbe64f70764ffe\"},\"headline\":\"Sicherheit und Zuverl\u00e4ssigkeit auf Schienen &#8211; Ein Einblick in unser neustes Projekt\",\"datePublished\":\"2024-04-25T11:10:43+00:00\",\"dateModified\":\"2024-04-25T11:39:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/sicherheit-und-zuverlaessigkeit-auf-schienen\\\/\"},\"wordCount\":178,\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/sicherheit-und-zuverlaessigkeit-auf-schienen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/newsInspection-and-assessment-of-carbody-cracks-and-corrosion.png\",\"keywords\":[\"Business\"],\"articleSection\":[\"Alle News\",\"Business\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/sicherheit-und-zuverlaessigkeit-auf-schienen\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/sicherheit-und-zuverlaessigkeit-auf-schienen\\\/\",\"name\":\"Sicherheit und Zuverl\u00e4ssigkeit auf Schienen - Ein Einblick in unser neustes Projekt - PROSE - Shaping tomorrow\u2019s mobility\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/sicherheit-und-zuverlaessigkeit-auf-schienen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/sicherheit-und-zuverlaessigkeit-auf-schienen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/newsInspection-and-assessment-of-carbody-cracks-and-corrosion.png\",\"datePublished\":\"2024-04-25T11:10:43+00:00\",\"dateModified\":\"2024-04-25T11:39:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/sicherheit-und-zuverlaessigkeit-auf-schienen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prose.one\\\/de\\\/sicherheit-und-zuverlaessigkeit-auf-schienen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/sicherheit-und-zuverlaessigkeit-auf-schienen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/newsInspection-and-assessment-of-carbody-cracks-and-corrosion.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/newsInspection-and-assessment-of-carbody-cracks-and-corrosion.png\",\"width\":2250,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/sicherheit-und-zuverlaessigkeit-auf-schienen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/prose.one\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sicherheit und Zuverl\u00e4ssigkeit auf Schienen &#8211; Ein Einblick in unser neustes Projekt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"name\":\"PROSE Shaping tomorrow\u2019s mobility\",\"description\":\"Shaping tomorrow\u2019s mobility\",\"publisher\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prose.one\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#organization\",\"name\":\"PROSE\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"contentUrl\":\"https:\\\/\\\/prose.one\\\/wp-content\\\/uploads\\\/PROSE_logo_rgb.png\",\"width\":1182,\"height\":326,\"caption\":\"PROSE\"},\"image\":{\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/prose-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prose.one\\\/de\\\/#\\\/schema\\\/person\\\/5dcf46831d13ad7f4ecbe64f70764ffe\",\"name\":\"Livia In-Albon\",\"url\":\"https:\\\/\\\/prose.one\\\/de\\\/author\\\/livia-in-albon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sicherheit und Zuverl\u00e4ssigkeit auf Schienen - Ein Einblick in unser neustes Projekt - PROSE - Shaping tomorrow\u2019s mobility","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/","og_locale":"de_DE","og_type":"article","og_title":"Sicherheit und Zuverl\u00e4ssigkeit auf Schienen - Ein Einblick in unser neustes Projekt - PROSE - Shaping tomorrow\u2019s mobility","og_description":"Bei PROSE sind wir stets bestrebt, die Sicherheit und Langlebigkeit der Fahrzeugflotten unserer Kund:innen zu maximieren. Bei unserem j\u00fcngsten Projekt haben wir umfassende Inspektionen an den X60A-Fahrzeugen durchgef\u00fchrt, um deren strukturelle Integrit\u00e4t sicherzustellen. Mit Hilfe von zerst\u00f6rungsfreien Pr\u00fcfungen, einschliesslich Magnetpulver- und Ultraschallpr\u00fcfungen, konnten wir Oberfl\u00e4chenfehler sowie innere Risse und Materialinhomogenit\u00e4ten identifizieren und dokumentieren. Diese gr\u00fcndlichen [&hellip;]","og_url":"https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/","og_site_name":"PROSE - Shaping tomorrow\u2019s mobility","article_published_time":"2024-04-25T11:10:43+00:00","article_modified_time":"2024-04-25T11:39:05+00:00","og_image":[{"url":"https:\/\/prose.one\/wp-content\/uploads\/newsInspection-and-assessment-of-carbody-cracks-and-corrosion.png","width":2250,"height":1500,"type":"image\/png"}],"author":"Livia In-Albon","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Livia In-Albon","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/#article","isPartOf":{"@id":"https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/"},"author":{"name":"Livia In-Albon","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/5dcf46831d13ad7f4ecbe64f70764ffe"},"headline":"Sicherheit und Zuverl\u00e4ssigkeit auf Schienen &#8211; Ein Einblick in unser neustes Projekt","datePublished":"2024-04-25T11:10:43+00:00","dateModified":"2024-04-25T11:39:05+00:00","mainEntityOfPage":{"@id":"https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/"},"wordCount":178,"publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"image":{"@id":"https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/newsInspection-and-assessment-of-carbody-cracks-and-corrosion.png","keywords":["Business"],"articleSection":["Alle News","Business"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/","url":"https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/","name":"Sicherheit und Zuverl\u00e4ssigkeit auf Schienen - Ein Einblick in unser neustes Projekt - PROSE - Shaping tomorrow\u2019s mobility","isPartOf":{"@id":"https:\/\/prose.one\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/#primaryimage"},"image":{"@id":"https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/#primaryimage"},"thumbnailUrl":"https:\/\/prose.one\/wp-content\/uploads\/newsInspection-and-assessment-of-carbody-cracks-and-corrosion.png","datePublished":"2024-04-25T11:10:43+00:00","dateModified":"2024-04-25T11:39:05+00:00","breadcrumb":{"@id":"https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/#primaryimage","url":"https:\/\/prose.one\/wp-content\/uploads\/newsInspection-and-assessment-of-carbody-cracks-and-corrosion.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/newsInspection-and-assessment-of-carbody-cracks-and-corrosion.png","width":2250,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/prose.one\/de\/sicherheit-und-zuverlaessigkeit-auf-schienen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/prose.one\/de\/"},{"@type":"ListItem","position":2,"name":"Sicherheit und Zuverl\u00e4ssigkeit auf Schienen &#8211; Ein Einblick in unser neustes Projekt"}]},{"@type":"WebSite","@id":"https:\/\/prose.one\/de\/#website","url":"https:\/\/prose.one\/de\/","name":"PROSE Shaping tomorrow\u2019s mobility","description":"Shaping tomorrow\u2019s mobility","publisher":{"@id":"https:\/\/prose.one\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prose.one\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/prose.one\/de\/#organization","name":"PROSE","url":"https:\/\/prose.one\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/","url":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","contentUrl":"https:\/\/prose.one\/wp-content\/uploads\/PROSE_logo_rgb.png","width":1182,"height":326,"caption":"PROSE"},"image":{"@id":"https:\/\/prose.one\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/prose-group"]},{"@type":"Person","@id":"https:\/\/prose.one\/de\/#\/schema\/person\/5dcf46831d13ad7f4ecbe64f70764ffe","name":"Livia In-Albon","url":"https:\/\/prose.one\/de\/author\/livia-in-albon\/"}]}},"_links":{"self":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/10565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/comments?post=10565"}],"version-history":[{"count":3,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/10565\/revisions"}],"predecessor-version":[{"id":10569,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/posts\/10565\/revisions\/10569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media\/10563"}],"wp:attachment":[{"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/media?parent=10565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/categories?post=10565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prose.one\/de\/wp-json\/wp\/v2\/tags?post=10565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}